{"id":69148,"date":"2024-12-06T11:58:19","date_gmt":"2024-12-06T10:58:19","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=69148"},"modified":"2024-12-06T11:58:19","modified_gmt":"2024-12-06T10:58:19","slug":"indiana-jones-e-lantico-cerchio-disponibile-learly-access","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/fr\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/","title":{"rendered":"Indiana Jones et le Cercle Antique\u00a0: Acc\u00e8s anticip\u00e9 disponible"},"content":{"rendered":"<p data-sourcepos=\"7:1-7:117\">Il nuovo capitolo videoludico con protagonista il leggendario archeologo \u00e8 disponibile da oggi in accesso anticipato.<\/p>\n<p data-sourcepos=\"7:1-7:117\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-66995\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/01\/indiana-jones-logo.webp\" alt=\"\" width=\"443\" height=\"140\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/01\/indiana-jones-logo.webp 1400w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/01\/indiana-jones-logo-790x249.webp 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/01\/indiana-jones-logo-1024x323.webp 1024w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/p>\n<p data-sourcepos=\"9:1-9:229\">Sviluppato da MachineGames, studio acclamato per la serie Wolfenstein, in collaborazione con Lucasfilm Games, Indiana Jones e l&#8217;Antico Cerchio promette un&#8217;esperienza cinematografica interattiva fedele allo spirito del franchise.<\/p>\n<p data-sourcepos=\"11:1-11:323\">Il gioco \u00e8 disponibile da oggi in Early Access per Xbox Series X|S, PC e Game Pass. I giocatori che acquisteranno la Premium Edition, il Premium Upgrade o la Collectors Edition potranno iniziare subito la loro avventura e avranno accesso al DLC Indiana Jones e l&#8217;Antico Cerchio: L&#8217;Ordine dei Giganti, previsto per il 2025. Ambientato tra gli eventi de I predatori dell&#8217;arca perduta e Indiana Jones e l&#8217;ultima crociata, il gioco offre una storia originale ricca di misteri archeologici, pericoli e intrighi. I giocatori potranno esplorare ambientazioni mozzafiato, risolvere enigmi complessi e cimentarsi in emozionanti combattimenti corpo a corpo, il tutto con l&#8217;inconfondibile stile di Indiana Jones.<\/p>\n<p style=\"text-align: center;\" data-sourcepos=\"11:1-11:323\"><figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_13930\"  width=\"1290\" height=\"726\"  data-origwidth=\"1290\" data-origheight=\"726\" src=\"https:\/\/www.youtube.com\/embed\/a9CIBW430os?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=1&fs=1&playsinline=0&autohide=2&hl=fr_FR&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"Lecteur YouTube\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/div><\/figure><\/p>\n<p data-sourcepos=\"15:1-15:188\">Il lancio ufficiale di Indiana Jones e l&#8217;Antico Cerchio \u00e8 previsto per il 9 dicembre su Xbox Series X|S, PC e Game Pass, mentre la versione PlayStation 5 arriver\u00e0 nella primavera del 2025.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il nuovo capitolo videoludico con protagonista il leggendario archeologo \u00e8 disponibile da oggi in accesso anticipato. Sviluppato da MachineGames, studio acclamato per la serie Wolfenstein, in collaborazione con Lucasfilm Games, Indiana Jones e l&#8217;Antico Cerchio promette un&#8217;esperienza cinematografica interattiva fedele allo spirito del franchise. Il gioco \u00e8 disponibile da oggi in Early Access per Xbox [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":68665,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-69148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indiana Jones e l&#039;Antico Cerchio: disponibile l&#039;early access<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/fr\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indiana Jones e l&#039;Antico Cerchio: disponibile l&#039;early access\" \/>\n<meta property=\"og:description\" content=\"Il nuovo capitolo videoludico con protagonista il leggendario archeologo \u00e8 disponibile da oggi in accesso anticipato. Sviluppato da MachineGames, studio acclamato per la serie Wolfenstein, in collaborazione con Lucasfilm Games, Indiana Jones e l&#8217;Antico Cerchio promette un&#8217;esperienza cinematografica interattiva fedele allo spirito del franchise. Il gioco \u00e8 disponibile da oggi in Early Access per Xbox [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/fr\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-06T10:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Indiana Jones e l&#8217;Antico Cerchio: disponibile l&#8217;early access\",\"datePublished\":\"2024-12-06T10:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Indiana-856498dfc83f7263b233.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/\",\"name\":\"Indiana Jones e l'Antico Cerchio: disponibile l'early access\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Indiana-856498dfc83f7263b233.jpg\",\"datePublished\":\"2024-12-06T10:58:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Indiana-856498dfc83f7263b233.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Indiana-856498dfc83f7263b233.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indiana Jones e l&#8217;Antico Cerchio: disponibile l&#8217;early access\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/fr\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indiana Jones e l'Antico Cerchio: disponibile l'early access","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/fr\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/","og_locale":"fr_FR","og_type":"article","og_title":"Indiana Jones e l'Antico Cerchio: disponibile l'early access","og_description":"Il nuovo capitolo videoludico con protagonista il leggendario archeologo \u00e8 disponibile da oggi in accesso anticipato. Sviluppato da MachineGames, studio acclamato per la serie Wolfenstein, in collaborazione con Lucasfilm Games, Indiana Jones e l&#8217;Antico Cerchio promette un&#8217;esperienza cinematografica interattiva fedele allo spirito del franchise. Il gioco \u00e8 disponibile da oggi in Early Access per Xbox [&hellip;]","og_url":"https:\/\/www.joypad.ch\/fr\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2024-12-06T10:58:19+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"\u00c9crit par":"Dave","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Indiana Jones e l&#8217;Antico Cerchio: disponibile l&#8217;early access","datePublished":"2024-12-06T10:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg","articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/","url":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/","name":"Indiana Jones e l'Antico Cerchio: disponibile l'early access","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg","datePublished":"2024-12-06T10:58:19+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/09\/Indiana-856498dfc83f7263b233.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/indiana-jones-e-lantico-cerchio-disponibile-learly-access\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Indiana Jones e l&#8217;Antico Cerchio: disponibile l&#8217;early access"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Le site de jeux vid\u00e9o, de technologie et de cin\u00e9ma pour le Tessin et la Suisse italophone","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"R\u00e9dacteur en chef de Joypad, vous le retrouverez aussi sur les r\u00e9seaux sociaux @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/fr\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/comments?post=69148"}],"version-history":[{"count":1,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69148\/revisions"}],"predecessor-version":[{"id":69149,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69148\/revisions\/69149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media\/68665"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media?parent=69148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/categories?post=69148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/tags?post=69148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}