{"id":69140,"date":"2024-12-05T17:40:36","date_gmt":"2024-12-05T16:40:36","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=69140"},"modified":"2024-12-05T17:40:53","modified_gmt":"2024-12-05T16:40:53","slug":"arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/fr\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/","title":{"rendered":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania"},"content":{"rendered":"<p style=\"text-align: justify;\" data-sourcepos=\"3:1-3:166\">ARCTIC, azienda nota per le soluzioni di raffreddamento, ha lanciato <strong>Senza<\/strong>, un PC desktop con un design innovativo pensato per essere montato sotto la scrivania.<\/p>\n<p style=\"text-align: justify;\" data-sourcepos=\"3:1-3:166\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-68953\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white.png\" alt=\"\" width=\"111\" height=\"121\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white.png 2007w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white-471x515.png 471w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white-936x1024.png 936w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white-1404x1536.png 1404w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/11\/ARCTIC_logo_white-1873x2048.png 1873w\" sizes=\"auto, (max-width: 111px) 100vw, 111px\" \/><\/p>\n<p style=\"text-align: justify;\" data-sourcepos=\"5:1-5:383\">Disponibile in tre configurazioni con processori AMD Ryzen serie 5000G, <a href=\"https:\/\/www.arctic.de\/en\/senza\/ACPCC00002A\">ARCTIC Senza<\/a> si distingue per il raffreddamento completamente passivo. L&#8217;assenza di ventole lo rende silenzioso e ideale per ambienti di lavoro o domestici dove la quiete \u00e8 fondamentale. Il case funge da dissipatore per la CPU, mentre l&#8217;SSD NVMe M.2 \u00e8 raffreddato dal dissipatore passivo ARCTIC M.2 Pro.<\/p>\n<p data-sourcepos=\"5:1-5:383\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69141\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px.jpg\" alt=\"\" width=\"2200\" height=\"1000\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px.jpg 2200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px-790x359.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px-1024x465.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px-1536x698.jpg 1536w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Back-Office_2200x1000px-2048x931.jpg 2048w\" sizes=\"auto, (max-width: 2200px) 100vw, 2200px\" \/><\/p>\n<p style=\"text-align: justify;\" data-sourcepos=\"7:1-7:297\">Senza offre diverse opzioni di connettivit\u00e0, tra cui Wi-Fi 6E, Bluetooth 5.3 e una porta LAN 2.5G. Supporta fino a due monitor connessi direttamente tramite HDMI e DisplayPort, con la possibilit\u00e0 di arrivare a quattro schermi tramite daisy chain. La risoluzione massima supportata \u00e8 5K a 60Hz.<\/p>\n<p style=\"text-align: justify;\" data-sourcepos=\"9:1-9:281\">Il pannello frontale, posizionabile a piacimento, integra le porte USB, le connessioni audio e il pulsante di accensione, garantendo un facile accesso. ARCTIC Senza \u00e8 venduto con Windows 11 Home N o Windows 11 Pro N preinstallato e privo di bloatware, pronto all&#8217;uso immediato.<\/p>\n<p style=\"text-align: justify;\" data-sourcepos=\"11:1-11:35\"><strong>Punti di forza di ARCTIC Senza:<\/strong><\/p>\n<ul data-sourcepos=\"13:1-20:0\">\n<li style=\"text-align: justify;\" data-sourcepos=\"13:1-13:47\">Design salvaspazio per una scrivania ordinata<\/li>\n<li style=\"text-align: justify;\" data-sourcepos=\"14:1-14:56\">Raffreddamento passivo per un funzionamento silenzioso<\/li>\n<li style=\"text-align: justify;\" data-sourcepos=\"15:1-15:62\">Connettivit\u00e0 completa con Wi-Fi 6E, Bluetooth 5.3 e LAN 2.5G<\/li>\n<li style=\"text-align: justify;\" data-sourcepos=\"16:1-16:34\">Supporto multi-monitor fino a 5K<\/li>\n<li style=\"text-align: justify;\" data-sourcepos=\"17:1-17:38\">Facilit\u00e0 di accesso alle connessioni<\/li>\n<li style=\"text-align: justify;\" data-sourcepos=\"18:1-20:0\">Sistema operativo preinstallato e senza bloatware<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69142\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg\" alt=\"\" width=\"2560\" height=\"1440\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg 2560w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement-1536x864.jpg 1536w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>ARCTIC, azienda nota per le soluzioni di raffreddamento, ha lanciato Senza, un PC desktop con un design innovativo pensato per essere montato sotto la scrivania. Disponibile in tre configurazioni con processori AMD Ryzen serie 5000G, ARCTIC Senza si distingue per il raffreddamento completamente passivo. L&#8217;assenza di ventole lo rende silenzioso e ideale per ambienti di [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":69142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-69140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/fr\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania\" \/>\n<meta property=\"og:description\" content=\"ARCTIC, azienda nota per le soluzioni di raffreddamento, ha lanciato Senza, un PC desktop con un design innovativo pensato per essere montato sotto la scrivania. Disponibile in tre configurazioni con processori AMD Ryzen serie 5000G, ARCTIC Senza si distingue per il raffreddamento completamente passivo. L&#8217;assenza di ventole lo rende silenzioso e ideale per ambienti di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/fr\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T16:40:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T16:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania\",\"datePublished\":\"2024-12-05T16:40:36+00:00\",\"dateModified\":\"2024-12-05T16:40:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/\"},\"wordCount\":223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/senza_Cablemanagement.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/\",\"name\":\"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/senza_Cablemanagement.jpg\",\"datePublished\":\"2024-12-05T16:40:36+00:00\",\"dateModified\":\"2024-12-05T16:40:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/senza_Cablemanagement.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/senza_Cablemanagement.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/fr\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/fr\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/","og_locale":"fr_FR","og_type":"article","og_title":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania","og_description":"ARCTIC, azienda nota per le soluzioni di raffreddamento, ha lanciato Senza, un PC desktop con un design innovativo pensato per essere montato sotto la scrivania. Disponibile in tre configurazioni con processori AMD Ryzen serie 5000G, ARCTIC Senza si distingue per il raffreddamento completamente passivo. L&#8217;assenza di ventole lo rende silenzioso e ideale per ambienti di [&hellip;]","og_url":"https:\/\/www.joypad.ch\/fr\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2024-12-05T16:40:36+00:00","article_modified_time":"2024-12-05T16:40:53+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"\u00c9crit par":"Dave","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania","datePublished":"2024-12-05T16:40:36+00:00","dateModified":"2024-12-05T16:40:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/"},"wordCount":223,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg","articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/","url":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/","name":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg","datePublished":"2024-12-05T16:40:36+00:00","dateModified":"2024-12-05T16:40:53+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2024\/12\/senza_Cablemanagement.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/arctic-senza-il-pc-silenzioso-che-scompare-sotto-la-scrivania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"ARCTIC Senza: il PC silenzioso che scompare sotto la scrivania"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Le site de jeux vid\u00e9o, de technologie et de cin\u00e9ma pour le Tessin et la Suisse italophone","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"R\u00e9dacteur en chef de Joypad, vous le retrouverez aussi sur les r\u00e9seaux sociaux @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/fr\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/comments?post=69140"}],"version-history":[{"count":2,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69140\/revisions"}],"predecessor-version":[{"id":69144,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/69140\/revisions\/69144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media\/69142"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media?parent=69140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/categories?post=69140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/tags?post=69140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}