{"id":62596,"date":"2022-01-05T16:10:31","date_gmt":"2022-01-05T15:10:31","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=62596"},"modified":"2022-01-05T16:10:31","modified_gmt":"2022-01-05T15:10:31","slug":"les-nouveaux-produits-samsung-presentes-au-ces-2022","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/fr\/le-novita-di-samsung-dal-ces-2022\/","title":{"rendered":"Derni\u00e8res nouvelles de Samsung au CES 2022"},"content":{"rendered":"<p style=\"text-align: justify;\">Il CES \u00e8 in pieno svolgimento e le novit\u00e0 arrivano senza fine. Samsung ha annunciato parecchie novit\u00e0 in campo monitor, TV e smartphones durante l&#8217;evento di Las Vegas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-50841\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2018\/07\/black-samsung-logo.png\" alt=\"\" width=\"321\" height=\"63\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2018\/07\/black-samsung-logo.png 2611w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2018\/07\/black-samsung-logo-790x155.png 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2018\/07\/black-samsung-logo-1024x201.png 1024w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Lineup schermi 2022<\/strong><\/h2>\n<p class=\"Fz(56px) Lh(60px) Fz(24px)!--sm Lh(28px)!--sm C(engadgetBlack) Mb(20px) Mt(20px)\"><strong>Odyssey Ark<\/strong><\/p>\n<p>Ark \u00e8 forse il display pi\u00f9 interessante e assurdo mostrato da Samsung, capace perfino di eclissare Neo G9 del 2021. Si tratta di uno schermo da 55 pollici 4K con aspect ratio 16:9, basato su tecnologia Quantum Dot Mini LED e pu\u00f2 ruotare su s\u00e9 stesso di 90 gradi per essere usato sia in verticale che orizzontale. La sua curvatura lo rende per\u00f2 pi\u00f9 simible a Neo G9, 1000R.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62602\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/odysseyark.jpg\" alt=\"\" width=\"675\" height=\"380\"><\/p>\n<p>Non abbiamo ancora molte informazioni su questo device ma potete vedere un&#8217;anteprima nel video qua sotto.<\/p>\n<p style=\"text-align: center;\"><figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_57951\"  width=\"1290\" height=\"726\"  data-origwidth=\"1290\" data-origheight=\"726\" src=\"https:\/\/www.youtube.com\/embed\/My-KUf_83u8?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=1&fs=1&playsinline=0&autohide=2&hl=fr_FR&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"Lecteur YouTube\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/div><\/figure><\/p>\n<p style=\"text-align: justify;\"><strong>Odyssey Neo G8<\/strong><br \/>\nPrimo monitor al mondo ad avere uno schermo curvo 4K (3840&#215;2160) 1000R con frequenza di aggiornamento di 240Hz e tempo di risposta di 1ms (GtG), si chiamer\u00e0 Odyssey Neo G8 32&#8243; (nome modello: G85NB). Basato su Quantum Mini LED, Quantum HDR 2000 con una luminosit\u00e0 di picco di 2.000nit e un rapporto di contrasto statico di un milione a uno. Il nuovo Odyssey Neo G8 \u00e8 costruito con un linguaggio di design simile a quello di Odyssey Neo G9, offrendo un elegante esterno bianco che spicca anche quando \u00e8 spento.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62597\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Odyssey-Neo-G8_left.jpg\" alt=\"\" width=\"785\" height=\"442\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Odyssey-Neo-G8_left.jpg 1365w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Odyssey-Neo-G8_left-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Odyssey-Neo-G8_left-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><\/p>\n<p><strong>Smart Monitor M8<\/strong><br \/>\nCon uno spessore ultrasottile di 11,4 mm, che \u00e8 circa tre quarti pi\u00f9 sottile del modello precedente, il 2022 Smart Monitor M8 32&#8243; (nome del modello: M80B) offre efficienza e spazio. Soprattutto per coloro che apprezzano lo stile, \u00e8 dotato di un sofisticato design flat-back con una maggiore usabilit\u00e0 ed \u00e8 disponibile in un nuovo colore bianco caldo che si adatta perfettamente ovunque. Il pannello UHD fornisce il 99% della gamma di colori sRGB mentre supporta 1,07 miliardi di colori a 400nit di luminosit\u00e0, mostrando ogni video, documento o foto con una precisione realistica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62599\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Smart-Monitor-M8_left.jpg\" alt=\"\" width=\"680\" height=\"530\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Smart-Monitor-M8_left.jpg 986w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Smart-Monitor-M8_left-661x515.jpg 661w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Smart TV e le app di produttivit\u00e0 sono integrate direttamente nel monitor, consentendo l&#8217;intrattenimento e il lavoro senza soluzione di continuit\u00e0 mentre serve come un hub di controllo SmartThings, anche senza la necessit\u00e0 di un PC. Il 2022 Smart Monitor M8 32&#8243; \u00e8 una buona opzione per il lavoro a distanza. Viene fornito con una SlimFit Cam magnetica mobile che consente videochiamate cristalline quando si lavora da casa. La sua applicazione Video Call integrata supporta le app di chiamata pi\u00f9 popolari, tra cui Google Duo. Con una porta USB Type-C che consente connessioni di ricarica a 65W, lo Smart Monitor M8 offre un&#8217;esperienza di lavoro all-in-one semplificata che non richiede una docking station aggiuntiva.<\/p>\n<p><strong>High Resolution Monitor S8<\/strong><br \/>\nIl Samsung High Resolution Monitor S8 (nome del modello: S80PB), disponibile nei modelli da 27&#8243; e 32&#8243;, offre prestazioni UHD di livello professionale per creatori e designer che hanno bisogno dei massimi livelli di precisione e portata quando lavorano in ufficio o a casa. Fornendo fino al 98% della gamma di colori DCI-P3, il S80PB fornisce una gamma ultra-ampia di colori ricchi e sfumati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62598\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right.jpg\" alt=\"\" width=\"710\" height=\"473\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right.jpg 1152w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right-773x515.jpg 773w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right-1024x683.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right-333x222.jpg 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right-240x160.jpg 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/High-res-Monitor-S8_right-360x240.jpg 360w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/p>\n<p style=\"text-align: justify;\">Come primo monitor al mondo UL (Underwriter Laboratories) verificato Glare Free, Matte Display \u00e8 applicato sulla parte superiore del pannello, riducendo il riflesso della luce anche quando non si usa un paraluce, per fornire un ambiente di lavoro senza distrazioni.&nbsp; Entrambi i modelli sono dotati di porte di ricarica e LAN USB Type-C 90W per aiutare gli utenti a creare una postazione di lavoro semplificata che pu\u00f2 caricare laptop e dispositivi mobili senza la necessit\u00e0 di una docking station aggiuntiva.<\/p>\n<h2><strong>Lineup TV 2022<\/strong><\/h2>\n<p>Per quanto riguarda le TV, Samsung sta per fare un enorme passo adottando la tecnologia QD OLED oltre che Micro LED e Neo QLED. Andiamo con ordine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62603\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2.jpg\" alt=\"\" width=\"844\" height=\"562\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2.jpg 1154w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2-774x515.jpg 774w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2-1024x681.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2-333x222.jpg 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2-240x160.jpg 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/MICRO-LED_2-360x240.jpg 360w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Micro LED<\/strong> offre una qualit\u00e0 d&#8217;immagine migliore della categoria grazie a 25 milioni di LED di dimensioni micrometriche che producono individualmente luce e colore, creando un&#8217;esperienza incredibilmente coinvolgente attraverso una profondit\u00e0 impressionante, colori vibranti e un elevato livello di chiarezza e contrasto. Al CES 2022, Samsung presenter\u00e0 il MICRO LED in tre diverse dimensioni &#8211; 110&#8243;, 101&#8243; e 89&#8243;. Oltre alle innovazioni hardware, Micro LED supporta la profondit\u00e0 della scala di grigi a 20 bit. Questo significa che i modelli Micro LED possono esprimere ogni dettaglio di una scena, offrendo il controllo pi\u00f9 fine con oltre 1 milione di passi di luminosit\u00e0 e livelli di colore, offrendo una vera esperienza HDR. Esprime anche il 100% della gamma di colori DCI e Adobe RGB, risultando in colori sorprendenti e realistici. Insieme al design immersivo reso possibile dal suo rapporto schermo\/corpo del 99,99%, MICRO LED offre prestazioni rivoluzionarie.<\/p>\n<p>Features:<\/p>\n<ul>\n<li>L&#8217;Art Mode permette ai consumatori di trasformare qualsiasi stanza in una galleria d&#8217;arte in quanto possono selezionare e visualizzare le loro opere d&#8217;arte preferite o la fotografia digitale. Il 2022 MICRO LED viene anche fornito con due esclusive opere d&#8217;arte del noto artista e designer Refik Anadol.<\/li>\n<li>Multi View consente agli utenti di visualizzare contenuti da quattro diverse fonti contemporaneamente &#8211; da qualsiasi o tutte le quattro porte HDMI &#8211; in incontaminata risoluzione 4K fino a 120fps.<\/li>\n<li>Dolby Atmos offre un&#8217;esperienza audio immersiva premier con altoparlanti canale superiore, laterale e inferiore per un suono mozzafiato, multi-dimensionale.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Grazie al Neo Quantum Processor e ai progressi nella tecnologia delle immagini e del suono che offre, il Neo <strong>QLED 2022<\/strong> fornir\u00e0 alcune delle immagini pi\u00f9 incontaminate e paesaggi sonori coinvolgenti possibili. Infatti, il processore Neo Quantum di quest&#8217;anno introduce la mappatura avanzata del contrasto con blu (unit\u00e0 di retroilluminazione), aumentando il livello di luminosit\u00e0 da 12 a 14-bit di gradazione per un maggiore controllo della fonte di luce &#8211; i Quantum Mini LED. Questo permette al televisore di controllare la sua illuminazione attraverso 16.384 zone, quadruplicati rispetto ai precedenti 4.096 zone. La nuova tecnologia Shape Adaptive Light sfrutta il Neo Quantum Processor per analizzare linee, forme e superfici e controllare la forma della luce dei Quantum Mini LED, migliorando la luminosit\u00e0 e la precisione di tutte le forme sullo schermo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62604\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1.png\" alt=\"\" width=\"812\" height=\"541\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1.png 1152w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1-773x515.png 773w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1-1024x683.png 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1-333x222.png 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1-240x160.png 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/Neo-QLED-8K_1-360x240.png 360w\" sizes=\"auto, (max-width: 812px) 100vw, 812px\" \/><\/p>\n<p>Ci saranno novit\u00e0 anche per quanto riguarda il <strong>Gaming Hub<\/strong>: Il Samsung Gaming Hub permetter\u00e0 ai giocatori di scoprire e saltare nei giochi che amano pi\u00f9 velocemente attraverso i servizi di streaming del gioco. I giocatori avranno accesso a una vasta libreria di giochi attraverso le partnership di Samsung con i leader del settore &#8211; NVIDIA GeForce Now, Stadia e Utomik. Le TV dotate di Smart Hub 2022 offiranno anche una calibrazione intelligente: questa funzione permette agli utenti di mettere a punto le impostazioni per una qualit\u00e0 d&#8217;immagine ottimale. La modalit\u00e0 base offre un modo semplice e veloce per calibrare gli schermi in 30 secondi, mentre la modalit\u00e0 professionale ottimizza gli schermi per una qualit\u00e0 dell&#8217;immagine perfetta in circa 10 minuti<\/p>\n<h2><strong>The Freestyle<\/strong><\/h2>\n<p style=\"text-align: justify;\">Paragrafo singolo per The Freestyle, un nuovo videoproiettore potenzialmente assai intrigante. Il proiettore Freestyle combina un altoparlante intelligente con l&#8217;illuminazione ambientale in un dispositivo facile da usare. Il Freestyle pesa solo 830 grammi e pu\u00f2 facilmente trasformare qualsiasi luogo in un cinema. A differenza dei proiettori convenzionali con linee angolari, il design versatile di The Freestyle consente una rotazione fino a 180 gradi, permettendo agli utenti di proiettare video di alta qualit\u00e0 su qualsiasi superficie &#8211; tavoli, pavimenti, pareti o anche soffitti &#8211; senza la necessit\u00e0 di uno schermo dedicato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62605\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2.jpg\" alt=\"\" width=\"744\" height=\"496\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2.jpg 1152w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2-773x515.jpg 773w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2-1024x683.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2-333x222.jpg 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2-240x160.jpg 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_02-2-360x240.jpg 360w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" \/><\/p>\n<p style=\"text-align: justify;\">Grazie alla tecnologia intelligente, The Freestyle ha una funzione di correzione della prospettiva e di regolazione del livello completamente automatica. Queste caratteristiche permettono alla telecamera di adattare automaticamente il display a qualsiasi superficie, da qualsiasi angolo, per presentare sempre un&#8217;immagine correttamente proporzionata. Inoltre, la funzione di messa a fuoco automatica del Freestyle permette un&#8217;immagine cristallina fino a 100 pollici in diagonale, su qualsiasi superficie e a qualsiasi angolo. Il Freestyle \u00e8 alimentato da batterie esterneUSB PD da 50W\/20V o pi\u00f9, permettendo agli utenti di avere un&#8217;alimentazione autonoma durante gli spostamenti, come ad esempio in campeggio.&nbsp; Quando non viene utilizzato come proiettore, The Freestyle pu\u00f2 anche generare effetti di luce ambientale utilizzando la sua modalit\u00e0 dedicata e il coperchio della lente traslucida. Freestyle agisce anche come un altoparlante intelligente, combinando la musica con vari effetti visivi che possono anche essere proiettati. Inoltre, The Freestyle ha funzionalit\u00e0 di TV connessa, duplicazione e trasmissione dello schermo compatibili con i dispositivi mobili Android e iOS.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-62606\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_03_logo-embedded.jpg\" alt=\"\" width=\"407\" height=\"575\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_03_logo-embedded.jpg 768w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_03_logo-embedded-364x515.jpg 364w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/The-Freestyle_Product-KV_03_logo-embedded-724x1024.jpg 724w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Il CES \u00e8 in pieno svolgimento e le novit\u00e0 arrivano senza fine. Samsung ha annunciato parecchie novit\u00e0 in campo monitor, TV e smartphones durante l&#8217;evento di Las Vegas. Lineup schermi 2022 Odyssey Ark Ark \u00e8 forse il display pi\u00f9 interessante e assurdo mostrato da Samsung, capace perfino di eclissare Neo G9 del 2021. Si tratta [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":62600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-62596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le novit\u00e0 di Samsung dal CES 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/fr\/les-nouveaux-produits-samsung-presentes-au-ces-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le novit\u00e0 di Samsung dal CES 2022\" \/>\n<meta property=\"og:description\" content=\"Il CES \u00e8 in pieno svolgimento e le novit\u00e0 arrivano senza fine. Samsung ha annunciato parecchie novit\u00e0 in campo monitor, TV e smartphones durante l&#8217;evento di Las Vegas. Lineup schermi 2022 Odyssey Ark Ark \u00e8 forse il display pi\u00f9 interessante e assurdo mostrato da Samsung, capace perfino di eclissare Neo G9 del 2021. Si tratta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/fr\/les-nouveaux-produits-samsung-presentes-au-ces-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T15:10:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1060\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Le novit\u00e0 di Samsung dal CES 2022\",\"datePublished\":\"2022-01-05T15:10:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/\"},\"wordCount\":1344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2022-Samsung-Monitor-lineup-3-models..jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/\",\"name\":\"Le novit\u00e0 di Samsung dal CES 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2022-Samsung-Monitor-lineup-3-models..jpg\",\"datePublished\":\"2022-01-05T15:10:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2022-Samsung-Monitor-lineup-3-models..jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2022-Samsung-Monitor-lineup-3-models..jpg\",\"width\":1060,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-samsung-dal-ces-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le novit\u00e0 di Samsung dal CES 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/fr\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Derni\u00e8res nouvelles de Samsung au CES 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/fr\/les-nouveaux-produits-samsung-presentes-au-ces-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"Le novit\u00e0 di Samsung dal CES 2022","og_description":"Il CES \u00e8 in pieno svolgimento e le novit\u00e0 arrivano senza fine. Samsung ha annunciato parecchie novit\u00e0 in campo monitor, TV e smartphones durante l&#8217;evento di Las Vegas. Lineup schermi 2022 Odyssey Ark Ark \u00e8 forse il display pi\u00f9 interessante e assurdo mostrato da Samsung, capace perfino di eclissare Neo G9 del 2021. Si tratta [&hellip;]","og_url":"https:\/\/www.joypad.ch\/fr\/les-nouveaux-produits-samsung-presentes-au-ces-2022\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2022-01-05T15:10:31+00:00","og_image":[{"width":1060,"height":768,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"\u00c9crit par":"Dave","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Le novit\u00e0 di Samsung dal CES 2022","datePublished":"2022-01-05T15:10:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/"},"wordCount":1344,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg","articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/","url":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/","name":"Derni\u00e8res nouvelles de Samsung au CES 2022","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg","datePublished":"2022-01-05T15:10:31+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/01\/2022-Samsung-Monitor-lineup-3-models..jpg","width":1060,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/le-novita-di-samsung-dal-ces-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Le novit\u00e0 di Samsung dal CES 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Le site de jeux vid\u00e9o, de technologie et de cin\u00e9ma pour le Tessin et la Suisse italophone","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"R\u00e9dacteur en chef de Joypad, vous le retrouverez aussi sur les r\u00e9seaux sociaux @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/fr\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/62596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/comments?post=62596"}],"version-history":[{"count":3,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/62596\/revisions"}],"predecessor-version":[{"id":62608,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/62596\/revisions\/62608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media\/62600"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media?parent=62596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/categories?post=62596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/tags?post=62596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}