{"id":53992,"date":"2019-06-06T08:56:28","date_gmt":"2019-06-06T06:56:28","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=53992"},"modified":"2019-11-22T17:04:12","modified_gmt":"2019-11-22T16:04:12","slug":"pokemon-epee-et-bouclier-toutes-les-informations-du-nintendo-direct","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/fr\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/","title":{"rendered":"Pok\u00e9mon \u00c9p\u00e9e et Bouclier : Toutes les informations du Nintendo Direct"},"content":{"rendered":"<p style=\"text-align: justify;\">Ieri pomeriggio The Pok\u00e9mon Company ha trasmesso un Pok\u00e9mon Direct dedicato ai prossimi main game: Pok\u00e9mon Spada e Scudo. Sono state rivelate nuove ed interessanti meccaniche che arricchiscono ulteriormente la serie, in primis i Pok\u00e9mon <strong>Dynamax<\/strong>, versioni ingigantite dei Pok\u00e9mon, capaci di scatenare attacchi potenti grazie alle loro generose dimensioni. Questi Pok\u00e9mon appaiono anche allo stato selvatico e potranno essere affrontati in una nuova modalit\u00e0 multiplayer chiamata <strong>Raid<\/strong>. I raid richiamano il concetto gi\u00e0 visto su Pok\u00e9mon GO: pi\u00f9 giocatori sono necessari per abbattere il Pok\u00e9mon gigante al fine di poterlo catturare. Questa speciale modalit\u00e0 multi giocatore sar\u00e0 disponibile solo in alcune porzioni della mappa di gioco, chiamate <strong>zone selvagge<\/strong>, le quali saranno liberamente esplorabili (con telecamera a prospettiva libera) \u00e0 la &#8220;The Legend of Zelda: Breath of the Wild&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53123\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/02\/Pokemon_Sword_Logo_IT_png_jpgcopy.jpg\" alt=\"\" width=\"600\" height=\"309\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/02\/Pokemon_Sword_Logo_IT_png_jpgcopy.jpg 3305w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/02\/Pokemon_Sword_Logo_IT_png_jpgcopy-790x407.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/02\/Pokemon_Sword_Logo_IT_png_jpgcopy-1024x528.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\">Molte altre informazioni saranno rivelate in futuro, di seguito trovate tutte le novit\u00e0 del Pok\u00e9mon Direct nel comunicato stampa trasmesso dalla societ\u00e0. Pok\u00e9mon Spada e Scudo saranno ad ogni modo disponibili il prossimo <strong>15 novembre<\/strong> in esclusiva su Nintendo Switch<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54001\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p20_03.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p20_03.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p20_03-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p20_03-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<div id=\"paragraph_heading_426533\" class=\"article__body\">\n<p style=\"text-align: justify;\"><em><b>Il fenomeno Dynamax<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Il fenomeno\u00a0Dynamax\u00a0si manifesta in determinati luoghi di Galar, permettendo ai Pok\u00e9mon di assumere dimensioni gigantesche durante la lotta, ed \u00e8 una componente fondamentale delle lotte Pok\u00e9mon che si svolgono in questa regione. I Pok\u00e9mon di Galar possono dynamaxizzarsi, ottenendo una forza inaudita e diventando ancora pi\u00f9 potenti. Gli Allenatori possono far dynamaxizzare un Pok\u00e9mon una volta sola per lotta, e il Pok\u00e9mon dynamaxizzato torner\u00e0 alla sua forma base dopo tre turni. Inoltre, solo gli Allenatori che hanno un Polsino Dynamax possono far dynamaxizzare i loro Pok\u00e9mon.<br \/>\nQuando un Pok\u00e9mon \u00e8 dynamaxizzato, tutte le sue mosse diventano speciali mosse Dynamax, delle mosse non solo potentissime, ma in certi casi anche dotate di effetti aggiuntivi. Un esempio \u00e8 Dynattacco, una mossa Dynamax di tipo Normale che ha l&#8217;effetto aggiuntivo di diminuire la Velocit\u00e0 degli avversari che colpisce. Le mosse <\/em><em>Dynamax dipendono dalle mosse che il Pok\u00e9mon conosce prima di dynamaxizzarsi e dal loro tipo.<br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53993\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p14_04_IT.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p14_04_IT.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p14_04_IT-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p14_04_IT-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><b><\/b><\/p>\n<p style=\"text-align: justify;\"><em><b>Le Palestre Pok\u00e9mon<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nella regione di Galar vi sono vari stadi che ospitano le Palestre, e in questi edifici si riuniscono Allenatori e Allenatrici specializzati in un determinato tipo. Per ottenere il titolo di Campione o Campionessa, i giocatori dovranno sconfiggere l&#8217;Allenatore pi\u00f9 forte di ogni Palestra, ovvero il Capopalestra. Le lotte contro i\u00a0<a title=\"Pok\u00e9mon Spada e Scudo, capipalestra, personaggi e stadi\" href=\"https:\/\/multiplayer.it\/notizie\/pokemon-spada-e-scudo-capipalestra-personaggi-e-stadi.html\">Capipalestra<\/a>, che spesso comportano scontri fra colossali Pok\u00e9mon dynamaxizzati, attirano un gran numero di spettatori e vengono trasmesse anche in televisione in tutta la regione di Galar. Uno di questi eccezionali Allenatori \u00e8 Yarrow, il Capopalestra di tipo Erba, nonch\u00e9 uno specialista degli scontri di lunga durata. \u00c8 molto amato dagli Allenatori della sua Palestra, e per lui quello che conta di pi\u00f9 nelle lotte \u00e8 divertirsi.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53994\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p04_02_IT.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p04_02_IT.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p04_02_IT-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p04_02_IT-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><b><\/b><\/em><\/p>\n<p style=\"text-align: justify;\"><em><b>Esplora le Terre Selvagge e partecipa a un Raid Dynamax<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Le Terre Selvagge sono vaste distese di natura incontaminata che si estendono nella regione di Galar. Questo tratto di natura selvaggia collega tra loro varie citt\u00e0 e paesi, e contiene una grandissima variet\u00e0 di Pok\u00e9mon, molto pi\u00f9 che in ogni altro angolo di Galar. Le specie che \u00e8 possibile trovare cambiano a seconda di diversi fattori, tra cui le condizioni atmosferiche e il punto in cui ci si trova, quindi le Terre Selvagge hanno qualcosa di nuovo da offrire a ogni visita. In quest&#8217;area, inoltre, i giocatori potranno esplorare le ampie distese in cerca di Pok\u00e9mon e strumenti in piena libert\u00e0, controllando la telecamera a piacimento.<br \/>\nNelle Terre Selvagge hanno luogo i Raid Dynamax, un nuovo tipo di lotta in cui ciascun giocatore dovr\u00e0 allearsi con altri tre Allenatori [1] per affrontare un Pok\u00e9mon Dynamax selvatico. Gli Allenatori avranno la possibilit\u00e0 di catturarlo se dovessero riuscire a sconfiggerlo&#8230; ma non sar\u00e0 facile. Il Pok\u00e9mon Dynamax selvatico, infatti, rimarr\u00e0 gigantesco e manterr\u00e0 i suoi poteri speciali per tutta la durata della lotta. Il gioco di squadra sar\u00e0 fondamentale, perch\u00e9 solo un membro del team potr\u00e0 dynamaxizzare un suo Pok\u00e9mon. Inoltre, alcuni Pok\u00e9mon si potranno catturare solo durante i Raid Dynamax. Lottando in squadra con altri tre amici tramite Nintendo Switch Online, i Raid Dynamax possono diventare ancora pi\u00f9 divertenti. Tuttavia, se non sono disponibili altri tre giocatori per affrontare la lotta contro il Pok\u00e9mon Dynamax selvatico, verranno scelti automaticamente degli Allenatori di supporto.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53995\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_05.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_05.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_05-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_05-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><b><\/b><\/em><\/p>\n<p style=\"text-align: justify;\"><em><b>La cultura e i personaggi di Galar<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>In Pok\u00e9mon Spada e Pok\u00e9mon Scudo, i giocatori viaggeranno nella regione di Galar e scopriranno molte localit\u00e0 singolari, come ad esempio citt\u00e0 dove uomini e Pok\u00e9mon lavorano fianco a fianco. Qui i Pok\u00e9mon hanno un ruolo molto importante, e sono molto richiesti da varie aziende per le loro abilit\u00e0 lavorative. Nella cultura di Galar, inoltre, le lotte Pok\u00e9mon costituiscono lo spettacolo pi\u00f9 amato. Si tengono negli stadi e attirano sempre grandi folle di fan e spettatori pronti a fare il tifo per i Capipalestra o i loro sfidanti. Allenatori di ogni provenienza si danno appuntamento alla Lega Pok\u00e9mon per sfidarsi e affinare le loro abilit\u00e0 nelle lotte. In quanto abitanti di Galar, i giocatori intraprenderanno il loro viaggio attraverso la regione e dovranno affrontare tutte le Palestre della regione e scalare la vetta della Lega Pok\u00e9mon per conquistare il titolo di Campione o Campionessa.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53996\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_06.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_06.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_06-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p18_06-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Lungo il cammino incontreranno moltissimi personaggi e Pok\u00e9mon diversi:<\/em><\/p>\n<ul>\n<li>Dandel \u00e8 il Campione in carica di Galar, e a tutt&#8217;oggi non ha mai subito una sconfitta in un incontro ufficiale. Apprezzatissimo sia per la sua abilit\u00e0 sia per la sua personalit\u00e0, Dandel \u00e8 ritenuto a pieno titolo il pi\u00f9 grande Allenatore di tutta Galar<\/li>\n<li>Hop \u00e8 il fratello minore di Dandel e il vicino di casa del giocatore. I due inizieranno la loro avventura lo stesso giorno, e il loro comune obiettivo di diventare Campioni li render\u00e0 rivali<\/li>\n<li>La Professoressa Flora \u00e8 la Professoressa della regione di Galar e si dedica alle ricerche sul fenomeno Dynamax<\/li>\n<li>Sonia \u00e8 la nipote nonch\u00e9 assistente della Professoressa Flora e un&#8217;amica d&#8217;infanzia di Dandel. \u00c8 una ricercatrice giovane ma dotata di una vasta conoscenza e sempre disposta a dispensare buoni consigli<\/li>\n<\/ul>\n<\/div>\n<div id=\"paragraph_heading_426534\" class=\"article__body\">\n<p style=\"text-align: justify;\"><em><b>I Pok\u00e9mon leggendari<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>I\u00a0Pok\u00e9mon leggendari\u00a0Zacian e Zamazenta sono avvolti da un fitto mistero persino per gli abitanti della regione di Galar. Zacian lotta muovendosi con tale grazia che riesce persino ad ammaliare i suoi avversari. In bocca regge quella che sembra essere una spada, la cui scintillante lama \u00e8 cos\u00ec affilata da poter fendere qualsiasi cosa. Con le sue movenze imponenti e il corpo ricoperto da quello che sembra essere uno scudo, Zamazenta riesce invece a respingere qualsiasi attacco e a sopraffare ogni avversario che osi affrontarlo.<\/em><\/p>\n<div id='gallery-1' class='gallery galleryid-53992 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.joypad.ch\/fr\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/package_zacian\/'><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"1024\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zacian-940x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zacian-940x1024.jpg 940w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zacian-473x515.jpg 473w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zacian.jpg 1200w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.joypad.ch\/fr\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/package_zamazenda\/'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1008\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda-1024x1008.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda-1024x1008.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda-523x515.jpg 523w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda-75x75.jpg 75w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Package_Zamazenda.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\"><em><br \/>\n<b>I primi compagni di viaggio<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Grookey, Scorbunny e Sobble sono i tre Pok\u00e9mon tra cui i giocatori potranno scegliere il loro primo compagno d&#8217;avventura. Ecco alcuni nuovi dettagli scoperti su di loro.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54000\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_03.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_03.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_03-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_03-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><br \/>\n<b>Grookey<\/b><br \/>\nCategoria: Pok\u00e9mon Scimpanz\u00e9<br \/>\nTipo: Erba<br \/>\nAltezza: 0,3 m<br \/>\nPeso: 5,0 kg<br \/>\nAbilit\u00e0: Erbaiuto<\/p>\n<p>La sua bacchetta, proveniente dalla foresta in cui vivono gruppi di questi Pok\u00e9mon, ha ottenuto poteri speciali per via dell&#8217;esposizione prolungata all&#8217;energia che Grookey produce assorbendo i raggi del sole con la sua pelliccia verde. Sembra che questo Pok\u00e9mon possa far riacquisire vivaci colori a foglie e fiori appassiti percuotendo la sua bacchetta vicino a loro.<\/p>\n<p><b>Scorbunny<\/b><br \/>\nCategoria: Pok\u00e9mon Coniglio<br \/>\nTipo: Fuoco<br \/>\nAltezza: 0,3 m<br \/>\nPeso: 4,5 kg<br \/>\nAbilit\u00e0: Aiutofuoco<\/p>\n<p>Grazie ai suoi potenti arti inferiori, Scorbunny corre e saltella attorno agli avversari confondendoli e disorientandoli. I cuscinetti sotto le sue zampe possono diventare ardenti, permettendogli di sferrare calci in grado di scottare il nemico. Grazie alla sacca nel petto che contiene densa energia infuocata, Scorbunny riesce ad accelerare il suo battito cardiaco e ad aumentare la sua temperatura corporea correndo di qua e di l\u00e0. In questo stato, Scorbunny riesce a tirare fuori tutta la potenza della sua energia infuocata, aumentando notevolmente la sua forza fisica.<\/p>\n<p><b>Sobble<\/b><br \/>\nCategoria: Pok\u00e9mon Acquacertola<br \/>\nTipo: Acqua<br \/>\nAltezza: 0,3 m<br \/>\nPeso: 4,0 kg<br \/>\nAbilit\u00e0: Acquaiuto<\/p>\n<p>Quando Sobble tocca l&#8217;acqua, il suo colore e il motivo sul suo corpo si modificano permettendogli di mimetizzarsi con l&#8217;ambiente circostante. Questo Pok\u00e9mon \u00e8 molto timoroso: quando \u00e8 nervoso o imbarazzato secerne acqua dal corpo come se fosse sudore e sparisce confondendosi con l&#8217;ambiente. Se si sente in pericolo, Sobble inizia a piangere disperatamente spargendo intorno lacrime dall&#8217;effetto portentoso, pari a quello di cento cipolle, facendo quindi scoppiare i presenti in un pianto incontrollabile. Dopodich\u00e9 approfitta del diversivo per scappare.<\/p>\n<p><b>I Pok\u00e9mon di Galar<\/b><\/p>\n<p>La regione di Galar ospita molte specie diverse di Pok\u00e9mon. Non ci sono ancora molte informazioni sulle caratteristiche biologiche di questi Pok\u00e9mon, tuttora oggetto di attento studio da parte di numerosi esperti.<\/p>\n<p><b>Gossifleur<\/b><br \/>\nCategoria: Pok\u00e9mon Fiorfronzolo<br \/>\nTipo: Erba<br \/>\nAltezza: 0,4 m<br \/>\nPeso: 2,2 kg<br \/>\nAbilit\u00e0: Lanugine\/Rigenergia<\/p>\n<p>Gossifleur predilige i luoghi caratterizzati da aria e acque pulite. Il suo polline ha propriet\u00e0 terapeutiche, ed \u00e8 comunemente usato a Galar come rimedio naturale sotto forma di tisana per i bambini ammalati. Si lascia trasportare dal vento per chilometri e chilometri e controlla la sua rotta piegando il corpo e i petali.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54002\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Gossifleur_Tournicoton_Cottini-75x75.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<b>Eldegoss<\/b><br \/>\nCategoria: Pok\u00e9mon Cotofronzolo<br \/>\nTipo: Erba<br \/>\nAltezza: 0,5 m<br \/>\nPeso: 2,5 kg<br \/>\nAbilit\u00e0: Lanugine\/Rigenergia<\/p>\n<p>Quando Gossifleur si evolve in Eldegoss, la sua testa si ricopre di una spessa lanugine che funge da cuscinetto, proteggendolo dai danni. Sembra che i suoi piccoli semi lanuginosi siano ricchi di sostanze nutritive che giovano sia alle persone che ai Pok\u00e9mon. Eldegoss sparge i suoi semi in tutta la regione, arricchendo cos\u00ec il terreno di Galar di sostanze nutritive.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54003\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Eldegoss_Blancoton_Cottomi-75x75.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<b>Wooloo<\/b><br \/>\nCategoria: Pok\u00e9mon Pecora<br \/>\nTipo: Normale<br \/>\nAltezza: 0,6 m<br \/>\nPeso: 6,0 kg<br \/>\nAbilit\u00e0: Morbidone\/Fugafacile<\/p>\n<p>Il vello bianco di Wooloo continua a crescere per tutta la vita, e se viene tosato a zero ricresce completamente nel giro di tre mesi. Se ne ricavano vestiti, tappeti e altri prodotti simili, specialit\u00e0 famose della regione di Galar. Wooloo vive in branco e copia costantemente il suo Allenatore o il capobranco. Non ama battersi e se serve fugge dai nemici rotolando.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54004\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Wooloo_Moumouton_Wolly-75x75.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<b>Corviknight<\/b><br \/>\nCategoria: Pok\u00e9mon Corvo<br \/>\nTipo: Volante\/Acciaio<br \/>\nAltezza: 2,2 m<br \/>\nPeso: 75,0 kg<br \/>\nAbilit\u00e0: Pressione\/Agitazione<\/p>\n<p>Corviknight, che spesso si pu\u00f2 vedere sfrecciare agile in volo, \u00e8 ritenuto il Pok\u00e9mon pi\u00f9 forte tra tutti quelli che popolano i cieli della regione di Galar. Molti affermano che qualunque Pok\u00e9mon abbastanza stolto da sfidarlo venga messo in fuga da un semplice sguardo feroce e dal grido di questo temibile avversario. Molti esemplari mettono la loro eccellente capacit\u00e0 di volo e grande intelligenza al servizio della societ\u00e0 Galar Trasporti trasportando persone da una citt\u00e0 all&#8217;altra.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54005\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Corviknight_Corvaillus_Krarmor-75x75.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><b>Drednaw<\/b><br \/>\nCategoria: Pok\u00e9mon Morso<br \/>\nTipo: Acqua\/Roccia<br \/>\nAltezza: 1,0 m<br \/>\nPeso: 115,5 kg<br \/>\nAbilit\u00e0: Ferromascella\/Guscioscudo<\/p>\n<p>Grazie ai suoi denti seghettati, Drednaw, il Pok\u00e9mon Morso, pu\u00f2 staccare pezzi di roccia e spezzare il ferro. Pur avendo una corazza molto pesante, riesce a muoversi rapidamente grazie ai muscoli particolarmente sviluppati. \u00c8 noto per la sua indole aggressiva, tanto che solo gli Allenatori pi\u00f9 abili riescono a controllarlo, e sembra che molti finiscano addirittura per rinunciare, facendolo tornare in natura.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-54006\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/Drednaw_Torgamord_Kamalm-75x75.jpg 75w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><b>I Pok\u00e9mon selvatici<\/b><br \/>\n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Quando i giocatori si imbatteranno nei Pok\u00e9mon selvatici che si possono vedere scorrazzare di qua e di l\u00e0 nell&#8217;erba alta o nelle grotte, partir\u00e0 la lotta. Alcuni Pok\u00e9mon inseguiranno i giocatori non appena li vedranno, mentre altri scapperanno via. L&#8217;icona a forma di &#8220;!&#8221; che apparir\u00e0 sull&#8217;erba alta indicher\u00e0 che l\u00ec \u00e8 nascosto un Pok\u00e9mon.<br \/>\nOgni Pok\u00e9mon ha un&#8217;abilit\u00e0, che pu\u00f2 avere determinati effetti nella lotta, durante l&#8217;esplorazione oppure in entrambe le circostanze. In Pok\u00e9mon Spada e Pok\u00e9mon Scudo, Gossifleur e Eldegoss possono avere l&#8217;abilit\u00e0 Lanugine. Grazie ad essa, se il Pok\u00e9mon subisce un attacco, sparge della lanugine che diminuisce la Velocit\u00e0 degli altri Pok\u00e9mon.<br \/>\nOgni volta che i giocatori vedranno o cattureranno un Pok\u00e9mon durante l&#8217;avventura in Pok\u00e9mon Spada e Pok\u00e9mon Scudo, le sue informazioni verranno registrate nel Pok\u00e9dex che, in questi giochi, fa parte dello Smart Rotom. In esso, naturalmente, si annida Rotom, un Pok\u00e9mon che ha l&#8217;abitudine di entrare negli apparecchi elettrici. Ma lo Smart Rotom \u00e8 molto pi\u00f9 di un semplice Pok\u00e9dex: ad esempio, pu\u00f2 essere collegato alla bici per farla avanzare pi\u00f9 velocemente sulla terraferma o, con qualche modifica alla bici stessa, pu\u00f2 addirittura permettere gli spostamenti sulla superficie dell&#8217;acqua.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-53999\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_05.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_05.jpg 1920w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_05-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p21_05-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ieri pomeriggio The Pok\u00e9mon Company ha trasmesso un Pok\u00e9mon Direct dedicato ai prossimi main game: Pok\u00e9mon Spada e Scudo. Sono state rivelate nuove ed interessanti meccaniche che arricchiscono ulteriormente la serie, in primis i Pok\u00e9mon Dynamax, versioni ingigantite dei Pok\u00e9mon, capaci di scatenare attacchi potenti grazie alle loro generose dimensioni. Questi Pok\u00e9mon appaiono anche allo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":54007,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-53992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/fr\/pokemon-epee-et-bouclier-toutes-les-informations-du-nintendo-direct\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct\" \/>\n<meta property=\"og:description\" content=\"Ieri pomeriggio The Pok\u00e9mon Company ha trasmesso un Pok\u00e9mon Direct dedicato ai prossimi main game: Pok\u00e9mon Spada e Scudo. Sono state rivelate nuove ed interessanti meccaniche che arricchiscono ulteriormente la serie, in primis i Pok\u00e9mon Dynamax, versioni ingigantite dei Pok\u00e9mon, capaci di scatenare attacchi potenti grazie alle loro generose dimensioni. Questi Pok\u00e9mon appaiono anche allo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/fr\/pokemon-epee-et-bouclier-toutes-les-informations-du-nintendo-direct\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-06T06:56:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T16:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pusti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pusti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/\"},\"author\":{\"name\":\"Pusti\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/4f730126867d8f9f0c4fb9009c964af3\"},\"headline\":\"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct\",\"datePublished\":\"2019-06-06T06:56:28+00:00\",\"dateModified\":\"2019-11-22T16:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/\"},\"wordCount\":2068,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/p17_02.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/\",\"name\":\"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/p17_02.jpg\",\"datePublished\":\"2019-06-06T06:56:28+00:00\",\"dateModified\":\"2019-11-22T16:04:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/p17_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/p17_02.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/4f730126867d8f9f0c4fb9009c964af3\",\"name\":\"Pusti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g\",\"caption\":\"Pusti\"},\"description\":\"Pusti \u00e8 uno degli storici co-redattori di Joypad.ch Avvocato, gaymer e climber, principalmente giocatore di console Nintendo e PC.\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/puda_\",\"www.linkedin.com\\\/in\\\/davide-pusterla\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/fr\\\/author\\\/pusti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pok\u00e9mon \u00c9p\u00e9e et Bouclier : Toutes les informations du Nintendo Direct","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/fr\/pokemon-epee-et-bouclier-toutes-les-informations-du-nintendo-direct\/","og_locale":"fr_FR","og_type":"article","og_title":"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct","og_description":"Ieri pomeriggio The Pok\u00e9mon Company ha trasmesso un Pok\u00e9mon Direct dedicato ai prossimi main game: Pok\u00e9mon Spada e Scudo. Sono state rivelate nuove ed interessanti meccaniche che arricchiscono ulteriormente la serie, in primis i Pok\u00e9mon Dynamax, versioni ingigantite dei Pok\u00e9mon, capaci di scatenare attacchi potenti grazie alle loro generose dimensioni. Questi Pok\u00e9mon appaiono anche allo [&hellip;]","og_url":"https:\/\/www.joypad.ch\/fr\/pokemon-epee-et-bouclier-toutes-les-informations-du-nintendo-direct\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2019-06-06T06:56:28+00:00","article_modified_time":"2019-11-22T16:04:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg","type":"image\/jpeg"}],"author":"Pusti","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"\u00c9crit par":"Pusti","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/"},"author":{"name":"Pusti","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/4f730126867d8f9f0c4fb9009c964af3"},"headline":"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct","datePublished":"2019-06-06T06:56:28+00:00","dateModified":"2019-11-22T16:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/"},"wordCount":2068,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg","articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/","url":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/","name":"Pok\u00e9mon \u00c9p\u00e9e et Bouclier : Toutes les informations du Nintendo Direct","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg","datePublished":"2019-06-06T06:56:28+00:00","dateModified":"2019-11-22T16:04:12+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2019\/06\/p17_02.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/pokemon-spada-e-scudo-tutte-le-informazioni-dal-nintendo-direct\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Pok\u00e9mon Spada e Scudo, tutte le informazioni dal Nintendo Direct"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Le site de jeux vid\u00e9o, de technologie et de cin\u00e9ma pour le Tessin et la Suisse italophone","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/4f730126867d8f9f0c4fb9009c964af3","name":"Laisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67f94cbea5a0d12706cad483e8287b619a78e25e07fb1fe6dbaeb592c56592bc?s=96&d=mm&r=g","caption":"Pusti"},"description":"Pusti est l&#039;un des r\u00e9dacteurs en chef de longue date de Joypad.ch. Avocat, militant pour la cause homosexuelle et grimpeur, il est principalement un joueur sur console Nintendo et PC.","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/puda_","www.linkedin.com\/in\/davide-pusterla"],"url":"https:\/\/www.joypad.ch\/fr\/author\/pusti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/53992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/comments?post=53992"}],"version-history":[{"count":0,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/53992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media\/54007"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media?parent=53992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/categories?post=53992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/tags?post=53992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}