{"id":22985,"date":"2014-10-18T16:25:00","date_gmt":"2014-10-18T14:25:00","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=22985"},"modified":"2014-10-18T16:27:28","modified_gmt":"2014-10-18T14:27:28","slug":"gabriel-knight-edition-du-20e-anniversaire","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/fr\/gabriel-knight-20th-anniversary-edition\/","title":{"rendered":"\u00c9dition du 20e anniversaire de Gabriel Knight"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Gabriel Knight<\/strong> \u00e8 una serie che va parecchio indietro nel tempo, il primo capitolo usc\u00ec infatti su MS-DOS da Sierra On-Line nel <strong>1993<\/strong>. L\u2019epoca d\u2019oro delle avventure grafiche ha dato i natali non solo a Gabriel Knight ma anche a Monkey Island, Maniac Mansion, Space Quest e molti altri. Il primo Gabriel Knight, dal titolo Sins of the Fathers fu un vero successo tanto da meritare una versione Limited Edition e una riedizione (corretta dai numerosi bug) su CD-Rom.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-13434\" alt=\"gkheader\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png\" width=\"530\" height=\"259\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png 648w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader-300x146.png 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">Il gioco \u00e8 uscito questa settimana in v<strong>ersione rimasterizzata<\/strong>: un sontuoso lavoro di ricostruzione del gioco originale adattandolo alla potenza dei computer moderni. Un vero e proprio<strong> atto d\u2019amore<\/strong> per i fan dello Shattenj\u00e4ger!<\/p>\n<h2 style=\"text-align: justify;\"><strong>Il Cacciatore di Ombre<\/strong><\/h2>\n<p style=\"text-align: justify;\">Gabriel Knight \u00e8 uno spiantato scrittore di romanzi incentrati su mistero e strani avvenimenti. \u00c8 anche padrone di una libreria, la St. George&#8217;s Rare Books, la quale per\u00f2 non \u00e8 che abbia chiss\u00e0 quanti clienti. Preso tra la sua indole flemmatica e la necessit\u00e0 di sbarcare il lunario, <strong>Gabriel ha deciso di scrivere un nuovo libro dedicato ai misteri del Voodoo<\/strong> e di un assassino che sembra agire secondo i suoi dettami. <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-22982\" alt=\"Bookstore03\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Bookstore03-1024x576.jpg\" width=\"664\" height=\"373\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Bookstore03-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Bookstore03-300x168.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Bookstore03.jpg 1364w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/>Ben presto saremo invischiati in un\u2019appassionante storia <strong>ambientata a New Orleans<\/strong>, tra assassini e poliziotti, gente altolocata e personaggi alquanto misteriosi! Pi\u00f9 di cos\u00ec per quanto riguarda la trama non vogliamo dire, anche perch\u00e9 un\u2019avventura grafica vive solo di questo: la trama!<\/p>\n<p style=\"text-align: justify;\">Gabriel Knight \u00e8, come detto in apertura,<strong> un opera creata per i fan di lunga data della serie<\/strong> e per far conoscere al pubblico questo storico personaggio. La sua creatrice, Jane Jensen (<a href=\"https:\/\/www.joypad.ch\/intervista-jane-jensen-creatrice-gabriel-knight\/\" target=\"_blank\">leggete qui l\u2019intervista<\/a> che abbiamo fatto con lei!) con <strong>Pinkerton Road e Phoenix Online Studios<\/strong> hanno fatto un ottimo lavoro, specialmente in un periodo in cui i \u201cremake HD\u201d si sprecano e hanno spesso qualit\u00e0 altalenanti. Questa 20th Anniversary Edition \u00e8 quasi uguale all\u2019originale, ma non potrebbe essere pi\u00f9 diversa. <strong>Grafica completamente ridisegnata<\/strong>, questa volta in alta risoluzione (ci mancherete pixelloni giganti!), audio e musiche riregistrate da zero e aggiustamenti anche per quanto riguarda l\u2019ordine degli enigmi e degli eventi. <strong>La storia \u00e8 rimasta invece invariata, come giusto che sia<\/strong>, anche se guadagna alcune piccole aggiunte.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22990\" alt=\"Moonbeam02\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Moonbeam02-1024x576.jpg\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Moonbeam02-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Moonbeam02-300x168.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/Moonbeam02.jpg 1364w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><\/h2>\n<h2 style=\"text-align: justify;\"><strong>Visitiamo New Orleans?<\/strong><\/h2>\n<p style=\"text-align: justify;\">L\u2019avventura di Gabriel ci poter\u00e0 in molteplici luoghi della citt\u00e0 americana, per parlare con gente, <strong>analizzare scene e ovviamente ragionando su quanto accade<\/strong>. Un\u2019avventura grafica in fondo \u00e8 proprio questo: molto backtracking e <strong>enigmi da risolvere<\/strong>. Grazie alla nuova grafica e alla tridimensionalit\u00e0 dei personaggi (che per\u00f2 continuano a ricordarmi troppo i Sims\u2026) il gioco ha guadagnato in fruibilit\u00e0 e piacere nell\u2019esplorazione. Rispetto al passato<strong> le cose sono state facilitate<\/strong>, con alcuni indizi nel sistema di discussione (le frasi che fanno progredire la storia sono evidenziate) e l\u2019aggiunta di numerosissimi contenuti extra (le note del diario) che al contempo aggiungono elementi alla partita e rendono le cose pi\u00f9 abbordabili. Chiaro, noi avremmo preferito la buona vecchia difficolt\u00e0 assurda delle avventure di una volta, ma non \u00e8 grave! Uno svecchiamento della meccanica di gioco \u00e8 stato sicuramente necessario per non alienare la \u201cclientela\u201d pi\u00f9 giovane, pi\u00f9 avvezza a sparatutto e titoli action.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22993\" alt=\"CastleMainHall03\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleMainHall03-1024x576.jpg\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleMainHall03-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleMainHall03-300x168.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleMainHall03.jpg 1364w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: justify;\">Graficamente il titolo<strong> \u00e8 davvero bello<\/strong>, specialmente per quanto riguarda i fondali. Un amalgama di novit\u00e0 visiva che si miscela alla <strong>magistrale storia soprannaturale scritta da Jane Jense<\/strong>n. Una storia che funziona oggi come allora, che cattura il giocatore per tenerlo avviluppato fino alla fine. Personaggi indimenticabili e una trama da vera scrittrice che ci fanno sperare in una riedizione anche dei capitoli 2 e 3 delle avventure di Knight. Ma quello che davvero vorremmo sarebbe una nuova storia, storia che magari diventer\u00e0 realt\u00e0 se questa edizione anniversario di <strong>The Sins of Fathers avr\u00e0 il successo che merita<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-22994\" alt=\"CastleChapel01\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleChapel01-1024x576.jpg\" width=\"762\" height=\"428\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleChapel01-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleChapel01-300x168.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/10\/CastleChapel01.jpg 1364w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/p>\n<p style=\"text-align: justify;\">Fan delle avventure grafiche, questo titolo va assaporato senza indugio alcuno! <strong>Se non siete avvezzi al genere, non potreste trovare di meglio con cui partire<\/strong>. Se invece conoscete (e amate) gi\u00e0 Gabriel Knight, non avete di certo avuto bisogno di leggere questa recensione! Il gioco \u00e8 disponibile su Steam per PC e Mac mentre arriver\u00e0 in un secondo momento su iOS e Android.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\">[youtube link=&#8221;http:\/\/youtu.be\/3yJrjg7s8mM&#8221; width=&#8221;690&#8243; height=&#8221;415&#8243;]<\/div>\n<p>&nbsp;<br \/>\n&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gabriel Knight \u00e8 una serie che va parecchio indietro nel tempo, il primo capitolo usc\u00ec infatti su MS-DOS da Sierra On-Line nel 1993. L\u2019epoca d\u2019oro delle avventure grafiche ha dato i natali non solo a Gabriel Knight ma anche a Monkey Island, Maniac Mansion, Space Quest e molti altri. Il primo Gabriel Knight, dal titolo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-22985","post","type-post","status-publish","format-standard","hentry","category-recensioni"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gabriel Knight 20th Anniversary Edition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/fr\/gabriel-knight-edition-du-20e-anniversaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabriel Knight 20th Anniversary Edition\" \/>\n<meta property=\"og:description\" content=\"Gabriel Knight \u00e8 una serie che va parecchio indietro nel tempo, il primo capitolo usc\u00ec infatti su MS-DOS da Sierra On-Line nel 1993. L\u2019epoca d\u2019oro delle avventure grafiche ha dato i natali non solo a Gabriel Knight ma anche a Monkey Island, Maniac Mansion, Space Quest e molti altri. Il primo Gabriel Knight, dal titolo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/fr\/gabriel-knight-edition-du-20e-anniversaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-18T14:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-18T14:27:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Gabriel Knight 20th Anniversary Edition\",\"datePublished\":\"2014-10-18T14:25:00+00:00\",\"dateModified\":\"2014-10-18T14:27:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/\"},\"wordCount\":690,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/gkheader.png\",\"articleSection\":[\"Recensione\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/\",\"name\":\"Gabriel Knight 20th Anniversary Edition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/gkheader.png\",\"datePublished\":\"2014-10-18T14:25:00+00:00\",\"dateModified\":\"2014-10-18T14:27:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/gkheader.png\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/gkheader.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/gabriel-knight-20th-anniversary-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabriel Knight 20th Anniversary Edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/fr\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9dition du 20e anniversaire de Gabriel Knight","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/fr\/gabriel-knight-edition-du-20e-anniversaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabriel Knight 20th Anniversary Edition","og_description":"Gabriel Knight \u00e8 una serie che va parecchio indietro nel tempo, il primo capitolo usc\u00ec infatti su MS-DOS da Sierra On-Line nel 1993. L\u2019epoca d\u2019oro delle avventure grafiche ha dato i natali non solo a Gabriel Knight ma anche a Monkey Island, Maniac Mansion, Space Quest e molti altri. Il primo Gabriel Knight, dal titolo [&hellip;]","og_url":"https:\/\/www.joypad.ch\/fr\/gabriel-knight-edition-du-20e-anniversaire\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2014-10-18T14:25:00+00:00","article_modified_time":"2014-10-18T14:27:28+00:00","og_image":[{"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png","type":"","width":"","height":""}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"\u00c9crit par":"Dave","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Gabriel Knight 20th Anniversary Edition","datePublished":"2014-10-18T14:25:00+00:00","dateModified":"2014-10-18T14:27:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/"},"wordCount":690,"commentCount":4,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png","articleSection":["Recensione"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/","url":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/","name":"\u00c9dition du 20e anniversaire de Gabriel Knight","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png","datePublished":"2014-10-18T14:25:00+00:00","dateModified":"2014-10-18T14:27:28+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2013\/10\/gkheader.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/gabriel-knight-20th-anniversary-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"Gabriel Knight 20th Anniversary Edition"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Le site de jeux vid\u00e9o, de technologie et de cin\u00e9ma pour le Tessin et la Suisse italophone","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"R\u00e9dacteur en chef de Joypad, vous le retrouverez aussi sur les r\u00e9seaux sociaux @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/fr\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/22985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/comments?post=22985"}],"version-history":[{"count":0,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/posts\/22985\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/media?parent=22985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/categories?post=22985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/fr\/wp-json\/wp\/v2\/tags?post=22985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}