{"id":66710,"date":"2023-12-10T12:08:27","date_gmt":"2023-12-10T11:08:27","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=66710"},"modified":"2023-12-10T12:08:27","modified_gmt":"2023-12-10T11:08:27","slug":"asus-introduces-the-first-computer-case-in-the-proart-line","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/en\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/","title":{"rendered":"ASUS Introduces First ProArt Computer Case"},"content":{"rendered":"<p style=\"text-align: justify;\">ASUS ha annunciato oggi il case ProArt PA602, che offre un eccezionale sistema di raffreddamento gi\u00e0 integrato ed \u00e8 il primo di molti case ProArt in arrivo. Con un pannello frontale progettato per massimizzare l&#8217;ingresso d&#8217;aria, un spesso ventilatore posteriore da 140 mm preinstallato, due ventilatori frontali da 200 mm e supporto per un radiatore da 420 mm, offre prestazioni termiche di alto livello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-57673\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2020\/04\/asus-logo-790x346.jpg\" alt=\"\" width=\"276\" height=\"121\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2020\/04\/asus-logo-790x346.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2020\/04\/asus-logo-1024x449.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2020\/04\/asus-logo.jpg 1182w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><\/p>\n<p style=\"text-align: justify;\">Il ProArt PA602 \u00e8 anche progettato per semplificare l&#8217;esperienza di costruzione del PC dell&#8217;utente con una gamma completa di funzionalit\u00e0 innovative ed \u00e8 pronto per un uso quotidiano conveniente con la rilevazione automatica della polvere, un controllo PWM integrato sulla serratura di alimentazione del pannello I\/O frontale e una ricca selezione di porte USB facilmente accessibili. Il tutto \u00e8 racchiuso in uno stile sofisticato e minimalista che lo rende un&#8217;aggiunta facile a qualsiasi studio, set o spazio creativo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-66711\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-515x515.png\" alt=\"\" width=\"515\" height=\"515\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-515x515.png 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-150x150.png 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-200x200.png 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-166x166.png 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-118x118.png 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-55x55.png 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1-75x75.png 75w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-1.png 600w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Prestazioni di raffreddamento straordinarie<\/strong><\/p>\n<p style=\"text-align: justify;\">Il case ProArt PA602 offre agli utenti la migliore soluzione per il raffreddamento completo e un funzionamento discreto. La sua capacit\u00e0 di raffreddamento inizia con un pannello frontale a griglia aperta, che presenta ampie fessure di ventilazione da 15,5 mm con una permeabilit\u00e0 del 45% e due ventilatori frontali ProArt da 200 mm preinstallati per garantire un flusso di raffreddamento non ostacolato nel case. Poich\u00e9 questi ventilatori sono molto pi\u00f9 spessi rispetto ai normali ventilatori da 120 mm o 140 mm, possono muovere un volume d&#8217;aria simile in modo molto pi\u00f9 silenzioso, offrendo agli utenti un incredibile equilibrio tra prestazioni e acustica. Questi robusti ventilatori con pale grandi hanno uno spessore di 38 mm e un ampio range di giri da 300 a 1000 rpm con controllo PWM, in modo da poter erogare un flusso d&#8217;aria notevolmente elevato rimanendo sorprendentemente silenziosi. Sono progettati per un flusso d&#8217;aria fino a 190,2 CFM, quasi il doppio di quanto offrono di solito i ventilatori di sistema da 200 mm. Un ventilatore posteriore da 140 mm preinstallato nel case ProArt PA602 aiuta a scaricare il calore e pu\u00f2 spegnersi completamente per un funzionamento silenzioso quando le temperature lo consentono.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-66712\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05414-WEB-600x900-1-343x515.jpg\" alt=\"\" width=\"343\" height=\"515\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05414-WEB-600x900-1-343x515.jpg 343w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05414-WEB-600x900-1.jpg 600w\" sizes=\"auto, (max-width: 343px) 100vw, 343px\" \/><\/p>\n<p style=\"text-align: justify;\">All&#8217;interno del case, i doppi deflettori d&#8217;aria aiutano a indirizzare l&#8217;aria di raffreddamento dove serve di pi\u00f9. Un pannello lungo il bordo anteriore del vassoio della scheda madre spinge delicatamente il flusso d&#8217;aria sopra il bordo superiore della scheda madre per ridurre la turbolenza e garantire un ottimo raffreddamento per la CPU e il circuito di alimentazione. Anche il coperchio dell&#8217;alimentatore ha un bordo anteriore angolato per dirigere il flusso d&#8217;aria verso la scheda grafica.<\/p>\n<p style=\"text-align: justify;\"><strong>Assemblaggio del PC facilitato con il case ProArt PA602<\/strong><\/p>\n<p style=\"text-align: justify;\">Il case ProArt PA602 va oltre per semplificare e razionalizzare il processo di costruzione del PC. In primo luogo, questo case PC offre molto spazio, anche per componenti di grandi dimensioni. Questo case \u00e8 pronto per schede madri fino a 12 pollici di lunghezza e 10,9 pollici di larghezza. Se gli utenti preferiscono un robusto dissipatore a torre per la loro CPU, scopriranno che l&#8217;altezza massima del dissipatore CPU di 190 mm fornita dal PA602 consente loro di scegliere tra praticamente tutte le opzioni sul mercato. Per coloro che considerano il raffreddamento a liquido, il supporto superiore per il radiatore supporta radiatori fino a 420 mm per un raffreddamento di alto livello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-66713\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-515x515.png\" alt=\"\" width=\"515\" height=\"515\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-515x515.png 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-150x150.png 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-200x200.png 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-166x166.png 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-118x118.png 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-55x55.png 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1-75x75.png 75w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/E_2400x2400-min-WEB-600x600-1.png 600w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<p style=\"text-align: justify;\">Progetti completati, risorse ad alta risoluzione e grandi set di dati possono richiedere una grande quantit\u00e0 di archiviazione. L&#8217;ampio interno del case ProArt PA602 offre agli utenti molte opzioni per installare un gran numero di unit\u00e0. Con il supporto per fino a otto SSD da 2,5 pollici, gli utenti saranno in grado di configurare rapidamente un&#8217;array di archiviazione grande e veloce, e il case include quattro alloggiamenti compatibili con HDD da 3,5 pollici. Per semplificare il processo di collegamento del pannello I\/O frontale alla scheda madre, abbiamo consolidato le funzioni chiave in un&#8217;unica intestazione unificata. Infine, il case ProArt PA602 riduce al minimo l&#8217;uso di utensili mentre gli utenti costruiscono e mantengono i loro PC. Entrambi i pannelli laterali si aprono con la pressione di un solo tasto. Il PA602 segna anche il debutto del meccanismo brevettato ed esclusivo ASUS per l&#8217;installazione delle schede aggiuntive PCIe, comprese le schede grafiche, senza la necessit\u00e0 di un cacciavite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66714\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05437-WEB-600x400-1.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05437-WEB-600x400-1.jpg 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05437-WEB-600x400-1-333x222.jpg 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05437-WEB-600x400-1-240x160.jpg 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/DSC05437-WEB-600x400-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Comodit\u00e0 quotidiane<\/strong><\/p>\n<p style=\"text-align: justify;\">Il case ProArt PA602 va oltre semplificare il processo di costruzione con tocchi riflessivi che razionalizzano l&#8217;esperienza quotidiana dell&#8217;utente con il proprio PC. I creatori spesso devono collegare una vasta gamma di periferiche e dispositivi di archiviazione esterni alle loro postazioni di lavoro, quindi il pannello I\/O frontale \u00e8 dotato di porte USB. L&#8217;elenco \u00e8 guidato da una veloce porta USB Type-C da 20 Gbps; abbina questo case a una scheda madre compatibile per sfruttarlo al massimo. Due porte USB Type-A da 5 Gbps e due porte USB 2.0 offrono agli utenti molte opzioni per collegare altri dispositivi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-66715\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-515x515.png\" alt=\"\" width=\"515\" height=\"515\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-515x515.png 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-150x150.png 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-200x200.png 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-166x166.png 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-118x118.png 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-55x55.png 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1-75x75.png 75w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/H_2400x2400-min-WEB-600x600-1.png 600w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<p style=\"text-align: justify;\">Se una spinta accidentale del pulsante di accensione ha mai ritardato uno dei progetti di un utente, apprezzeranno il blocco fisico del pulsante di accensione sul ProArt PA602. Questo semplice meccanismo impedisce che il pulsante di accensione venga premuto accidentalmente. Per rallentare l&#8217;accumulo di polvere all&#8217;interno del case, il case ProArt PA602 include filtri antipolvere staccabili sui pannelli anteriore, superiore e inferiore. Il PA602 presenta anche un sistema che rileva automaticamente quanto polvere, microfibra e altre particelle si sono accumulate sul filtro anteriore e illuminer\u00e0 un LED sul lato del case quando \u00e8 il momento di pulire i filtri.<\/p>\n<p style=\"text-align: justify;\"><strong>Design sofisticato<\/strong><\/p>\n<p style=\"text-align: justify;\">Con il suo design minimalista basato su linee pulite e una piacevole simmetria, il case ProArt PA602 ha un&#8217;estetica che non \u00e8 mai fuori luogo. Il pannello laterale in vetro temperato invita a uno sguardo pi\u00f9 ravvicinato all&#8217;hardware all&#8217;interno, ma \u00e8 anche oscurato per ridurre al minimo qualsiasi distrazione in modo che gli utenti possano mantenere la loro concentrazione sul flusso di lavoro. Gli utenti possono abbinare il ProArt PA602 ad altri componenti ProArt, tra cui schede madri ASUS ProArt, il raffreddatore liquido AIO ProArt LC 420 e le schede grafiche ProArt, per costruire un PC con un aspetto coerente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-66716\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-515x515.png\" alt=\"\" width=\"515\" height=\"515\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-515x515.png 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-150x150.png 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-200x200.png 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-166x166.png 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-118x118.png 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-55x55.png 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1-75x75.png 75w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/T_2400x2400-min-WEB-600x600-1.png 600w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Availability and price<\/strong><\/p>\n<p style=\"text-align: justify;\">Il case ProArt PA602 sar\u00e0 disponibile dalla fine di dicembre in Germania, Austria e Svizzera al prezzo consigliato al pubblico di 229,90 EUR \/ CHF IVA inclusa presso rivenditori specializzati e online e nello shop online ASUS (DE\/AT &amp; CH).<\/p>","protected":false},"excerpt":{"rendered":"<p>ASUS ha annunciato oggi il case ProArt PA602, che offre un eccezionale sistema di raffreddamento gi\u00e0 integrato ed \u00e8 il primo di molti case ProArt in arrivo. Con un pannello frontale progettato per massimizzare l&#8217;ingresso d&#8217;aria, un spesso ventilatore posteriore da 140 mm preinstallato, due ventilatori frontali da 200 mm e supporto per un radiatore [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":66717,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-66710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASUS presenta il primo case per computer della linea ProArt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/en\/asus-introduces-the-first-computer-case-in-the-proart-line\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASUS presenta il primo case per computer della linea ProArt\" \/>\n<meta property=\"og:description\" content=\"ASUS ha annunciato oggi il case ProArt PA602, che offre un eccezionale sistema di raffreddamento gi\u00e0 integrato ed \u00e8 il primo di molti case ProArt in arrivo. Con un pannello frontale progettato per massimizzare l&#8217;ingresso d&#8217;aria, un spesso ventilatore posteriore da 140 mm preinstallato, due ventilatori frontali da 200 mm e supporto per un radiatore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/en\/asus-introduces-the-first-computer-case-in-the-proart-line\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-10T11:08:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"ASUS presenta il primo case per computer della linea ProArt\",\"datePublished\":\"2023-12-10T11:08:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/\"},\"wordCount\":1043,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/F_2400x2400-min-WEB-600x600-2.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/\",\"name\":\"ASUS presenta il primo case per computer della linea ProArt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/F_2400x2400-min-WEB-600x600-2.png\",\"datePublished\":\"2023-12-10T11:08:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/F_2400x2400-min-WEB-600x600-2.png\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/F_2400x2400-min-WEB-600x600-2.png\",\"width\":970,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/asus-presenta-il-primo-case-per-computer-della-linea-proart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ASUS presenta il primo case per computer della linea ProArt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/en\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASUS Introduces First ProArt Computer Case","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/en\/asus-introduces-the-first-computer-case-in-the-proart-line\/","og_locale":"en_US","og_type":"article","og_title":"ASUS presenta il primo case per computer della linea ProArt","og_description":"ASUS ha annunciato oggi il case ProArt PA602, che offre un eccezionale sistema di raffreddamento gi\u00e0 integrato ed \u00e8 il primo di molti case ProArt in arrivo. Con un pannello frontale progettato per massimizzare l&#8217;ingresso d&#8217;aria, un spesso ventilatore posteriore da 140 mm preinstallato, due ventilatori frontali da 200 mm e supporto per un radiatore [&hellip;]","og_url":"https:\/\/www.joypad.ch\/en\/asus-introduces-the-first-computer-case-in-the-proart-line\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2023-12-10T11:08:27+00:00","og_image":[{"width":970,"height":617,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png","type":"image\/png"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Written by":"Dave","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"ASUS presenta il primo case per computer della linea ProArt","datePublished":"2023-12-10T11:08:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/"},"wordCount":1043,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/","url":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/","name":"ASUS Introduces First ProArt Computer Case","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png","datePublished":"2023-12-10T11:08:27+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/12\/F_2400x2400-min-WEB-600x600-2.png","width":970,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/asus-presenta-il-primo-case-per-computer-della-linea-proart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"ASUS presenta il primo case per computer della linea ProArt"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"The video game, technology, and film website for Ticino and Italian-speaking Switzerland","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Editor-in-Chief of Joypad, you can also find him on social media @MrPipistro.","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/en\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts\/66710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/comments?post=66710"}],"version-history":[{"count":1,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts\/66710\/revisions"}],"predecessor-version":[{"id":66718,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts\/66710\/revisions\/66718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/media\/66717"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/media?parent=66710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/categories?post=66710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/tags?post=66710"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}