{"id":30424,"date":"2015-08-07T19:31:17","date_gmt":"2015-08-07T17:31:17","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=30424"},"modified":"2015-08-08T16:10:46","modified_gmt":"2015-08-08T14:10:46","slug":"ubisoft-and-virtual-reality-at-gamescom","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/en\/ubisoft-e-la-realta-virtuale-alla-gamescom\/","title":{"rendered":"Ubisoft and virtual reality at Gamescom"},"content":{"rendered":"<p style=\"text-align: justify;\">Allo stand Ubisoft di quest\u2019anno non c\u2019erano solo Assassin\u2019s Creed e Rainbow Six ma anche qualche produzione pi\u00f9 sperimentale e interessante. Eagle Eye, proof of concept mostrato dal Ubisoft Montreal \u00e8 un progetto per dimostrare l\u2019applicazione della realt\u00e0 virtuale in situazioni di gioco reale. Indossato un Oculus DK2 e imbracciato un controller di Xbox 360, ci siamo fatti un giretto nella VR secondo Ubi.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-2465\" alt=\"ubisoft-logo-horizontal\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg\" width=\"641\" height=\"173\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg 1000w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale-300x81.jpg 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/p>\n<p style=\"text-align: justify;\">In Eagle Eye siamo dentro la testa di una maestosa aquila che sorvola una mappa stilizzata di Parigi presa direttamente dall\u2019ultimo Assassins\u2019 Creed. Tramite i movimenti della testa possiamo indirizzare il volo del rapace, con il pad invece potevamo accelerare o rallentare. Scopo della tech demo era di raccogliere una bandiera e portarla in un punto luminoso nel cielo. Una sorta di cattura la bandiera 2v2 a colpi di urli di aquila e di virate mozzafiato tra i vicoli della citt\u00e0. Inizialmente, durante la fase di \u201criscaldamento\u201d in cui abbiamo potuto svolazzare tranquillamente sentivo un pochino di nausea che per\u00f2 \u00e8 scomparsa immediatamente la mia mente si \u00e8 concentrata sulla sfida. Eagle Eye \u00e8 divertente e immediato ed \u00e8 la dimostrazione che un concetto semplicissimo come questo funziona alla grande. La seconda demo che ho visto era la famosa scena di Far Cry 3 in cui Vaas si interroga sul significato della parola \u201cinsania\u201d. La scena era per\u00f2 in prima persona, nel senso che ero io legato ad un mattone in cima ad un burrone con un fiume minaccioso in fondo. Dopo aver farneticato per un po\u2019, Vaas mi ha spinto gi\u00f9 nell\u2019acqua e la demo si \u00e8 conclusa. Un altro proof of concept che dimostra come Ubisoft stia sperimentando non solo gameplay ma anche story telling in realt\u00e0 virtuale. Questa demo non era molto impressionante a livello tecnico e serviva solo a dimostrare che vivere una scena in prima persona, con gli occhi del personaggio, cambia le cose a livello emotivo. I ragazzi di Ubisoft Montreal non si sono di certo sbilanciati, ma hanno rivelato che stanno preparando titoli VR per uscire al lancio dei vari Oculus, Vive e compagni. Non ci resta che aspettare.<\/p>","protected":false},"excerpt":{"rendered":"<p>Allo stand Ubisoft di quest\u2019anno non c\u2019erano solo Assassin\u2019s Creed e Rainbow Six ma anche qualche produzione pi\u00f9 sperimentale e interessante. Eagle Eye, proof of concept mostrato dal Ubisoft Montreal \u00e8 un progetto per dimostrare l\u2019applicazione della realt\u00e0 virtuale in situazioni di gioco reale. Indossato un Oculus DK2 e imbracciato un controller di Xbox 360, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[571,601],"tags":[],"class_list":["post-30424","post","type-post","status-publish","format-standard","hentry","category-gamescom15","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ubisoft e la realt\u00e0 virtuale alla Gamescom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/en\/ubisoft-and-virtual-reality-at-gamescom\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ubisoft e la realt\u00e0 virtuale alla Gamescom\" \/>\n<meta property=\"og:description\" content=\"Allo stand Ubisoft di quest\u2019anno non c\u2019erano solo Assassin\u2019s Creed e Rainbow Six ma anche qualche produzione pi\u00f9 sperimentale e interessante. Eagle Eye, proof of concept mostrato dal Ubisoft Montreal \u00e8 un progetto per dimostrare l\u2019applicazione della realt\u00e0 virtuale in situazioni di gioco reale. Indossato un Oculus DK2 e imbracciato un controller di Xbox 360, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/en\/ubisoft-and-virtual-reality-at-gamescom\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-07T17:31:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-08T14:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Ubisoft e la realt\u00e0 virtuale alla Gamescom\",\"datePublished\":\"2015-08-07T17:31:17+00:00\",\"dateModified\":\"2015-08-08T14:10:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/ubisoft-logo-orizzontale.jpg\",\"articleSection\":[\"Gamescom 2015\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/\",\"name\":\"Ubisoft e la realt\u00e0 virtuale alla Gamescom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/ubisoft-logo-orizzontale.jpg\",\"datePublished\":\"2015-08-07T17:31:17+00:00\",\"dateModified\":\"2015-08-08T14:10:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/ubisoft-logo-orizzontale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/ubisoft-logo-orizzontale.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/ubisoft-e-la-realta-virtuale-alla-gamescom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamescom 2015\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/gamescom15\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ubisoft e la realt\u00e0 virtuale alla Gamescom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/en\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ubisoft and virtual reality at Gamescom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/en\/ubisoft-and-virtual-reality-at-gamescom\/","og_locale":"en_US","og_type":"article","og_title":"Ubisoft e la realt\u00e0 virtuale alla Gamescom","og_description":"Allo stand Ubisoft di quest\u2019anno non c\u2019erano solo Assassin\u2019s Creed e Rainbow Six ma anche qualche produzione pi\u00f9 sperimentale e interessante. Eagle Eye, proof of concept mostrato dal Ubisoft Montreal \u00e8 un progetto per dimostrare l\u2019applicazione della realt\u00e0 virtuale in situazioni di gioco reale. Indossato un Oculus DK2 e imbracciato un controller di Xbox 360, [&hellip;]","og_url":"https:\/\/www.joypad.ch\/en\/ubisoft-and-virtual-reality-at-gamescom\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2015-08-07T17:31:17+00:00","article_modified_time":"2015-08-08T14:10:46+00:00","og_image":[{"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg","type":"","width":"","height":""}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Written by":"Dave","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Ubisoft e la realt\u00e0 virtuale alla Gamescom","datePublished":"2015-08-07T17:31:17+00:00","dateModified":"2015-08-08T14:10:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg","articleSection":["Gamescom 2015","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/","url":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/","name":"Ubisoft and virtual reality at Gamescom","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg","datePublished":"2015-08-07T17:31:17+00:00","dateModified":"2015-08-08T14:10:46+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2012\/06\/ubisoft-logo-orizzontale.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/ubisoft-e-la-realta-virtuale-alla-gamescom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Gamescom 2015","item":"https:\/\/www.joypad.ch\/news\/gamescom15\/"},{"@type":"ListItem","position":4,"name":"Ubisoft e la realt\u00e0 virtuale alla Gamescom"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"The video game, technology, and film website for Ticino and Italian-speaking Switzerland","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Editor-in-Chief of Joypad, you can also find him on social media @MrPipistro.","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/en\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts\/30424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/comments?post=30424"}],"version-history":[{"count":0,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/posts\/30424\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/media?parent=30424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/categories?post=30424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/en\/wp-json\/wp\/v2\/tags?post=30424"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}