{"id":66277,"date":"2023-10-05T09:16:08","date_gmt":"2023-10-05T07:16:08","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=66277"},"modified":"2023-10-05T09:16:08","modified_gmt":"2023-10-05T07:16:08","slug":"google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/de\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/","title":{"rendered":"Google bringt Pixel 8, Pixel Pro 8, Pixel Buds Pro und Pixel Watch 2 in der Schweiz auf den Markt."},"content":{"rendered":"<p style=\"text-align: justify;\">Google o tutto o niente, sembra! Dopo anni passati a guardare con interesse, ma da lontano, la gamma di smartphones del gigante statunitense, ora Google si appresta a lanciare un gran numero di devices sul mercato elvetico: smartphones, earbuds e orologi!<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-45433\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/12\/2000px-Google_2015_logo.svg_.png\" alt=\"\" width=\"263\" height=\"89\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/12\/2000px-Google_2015_logo.svg_.png 2000w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/12\/2000px-Google_2015_logo.svg_-790x267.png 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/12\/2000px-Google_2015_logo.svg_-1024x346.png 1024w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Pixel 8, Pixel 8 Pro e Pixel 7a<\/strong><\/h2>\n<p style=\"text-align: justify;\">In vendita in Svizzera a partire dal 12 ottobre 2023,&nbsp; Pixel 8 e Pixel 8 Pro, sono due smartphone sviluppati da Google e alimentati dall&#8217;intelligenza artificiale per un&#8217;esperienza ancora pi\u00f9 pratica e personalizzata. Questi dispositivi sono ricchi di nuove funzionalit\u00e0, tutte alimentate dal chip Google Tensor G3. Ecco una panoramica di tutto ci\u00f2 che offrono, dal design ai nuovi sensori, passando per le fotocamere all&#8217;avanguardia e molto altro.<\/p>\n<figure id=\"attachment_66278\" aria-describedby=\"caption-attachment-66278\" style=\"width: 879px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-66278\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro_Bay.jpg\" alt=\"\" width=\"879\" height=\"493\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro_Bay.jpg 879w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro_Bay-790x443.jpg 790w\" sizes=\"auto, (max-width: 879px) 100vw, 879px\" \/><figcaption id=\"caption-attachment-66278\" class=\"wp-caption-text\">Pixel 8 Pro<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con bordi arrotondati e dimensioni pi\u00f9 compatte rispetto al loro predecessore, offrono una presa comoda. Il display da 6,2 pollici di Pixel 8 offre una chiarezza estremamente realistica. Disponibile nei colori Verde Salvia, Nero Vulcanico e Rosa, Pixel 8 presenta una finitura metallica satinata e vetro lucido sul retro. Il display Super Actua da 6,7 pollici di Pixel 8 Pro \u00e8 il pi\u00f9 luminoso mai prodotto da Google. Anche alla luce diretta del sole, la qualit\u00e0 delle sue immagini ultra HDR \u00e8 perfetta. Il display completamente piatto offre un&#8217;esperienza pi\u00f9 coinvolgente con pi\u00f9 spazio. Ha anche un retro in vetro opaco con cornice in alluminio ed \u00e8 disponibile in tre colori: Blu Azzurro, Nero Vulcanico e Porcellana. Posizionato sul retro del Pixel 8 Pro, un nuovo sensore di temperatura consente di scansionare rapidamente un oggetto per conoscere la sua temperatura. Una funzione molto utile per sapere se la padella \u00e8 abbastanza calda per iniziare la cottura o se il latte nel biberon del bambino \u00e8 alla temperatura giusta.<\/p>\n<figure id=\"attachment_66279\" aria-describedby=\"caption-attachment-66279\" style=\"width: 849px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-66279\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8_Hazel.jpg\" alt=\"\" width=\"849\" height=\"481\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8_Hazel.jpg 849w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8_Hazel-790x448.jpg 790w\" sizes=\"auto, (max-width: 849px) 100vw, 849px\" \/><figcaption id=\"caption-attachment-66279\" class=\"wp-caption-text\">Pixel 8<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Nuove migliorie per la fotocamera<\/strong><\/p>\n<p style=\"text-align: justify;\">Pixel 8 e Pixel 8 Pro sono dotati di potenti sistemi fotografici aggiornati che consentono di scattare foto e video di eccezionale qualit\u00e0, oltre a offrire strumenti di editing innovativi. Tutti i sensori fotografici del Pixel 8 Pro sono stati aggiornati. Il modulo ultra-grandangolare, ora pi\u00f9 grande, consente una messa a fuoco macro ancora migliore. La telecamera scatta foto con uno zoom ottico 5x. Il modulo fotografico anteriore ora dispone della messa a fuoco automatica per ottenere i migliori selfie su uno smartphone Pixel. Pixel 8 \u00e8 dotato dello stesso modulo fotografico principale aggiornato, oltre a una nuova lente grandangolare per la messa a fuoco macro. L&#8217;applicazione fotocamera ha un&#8217;interfaccia intuitiva con un design rivisitato per trovare e catturare rapidamente contenuti nei modi foto e video preferiti. Pixel 8 Pro consente di accedere alla modalit\u00e0 Pro per un maggiore controllo creativo sul modulo fotocamera Pixel, con impostazioni come il tempo di esposizione, l&#8217;ISO, foto da 50 MP su tutta la gamma di zoom e molto altro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-66280\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Hazel_Bay.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Hazel_Bay.jpg 960w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Hazel_Bay-687x515.jpg 687w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Nuovi strumenti di editing<\/strong><\/p>\n<p style=\"text-align: justify;\">A volte capita che la foto di gruppo sia perfetta, ma una persona non guardi l&#8217;obiettivo. La funzione &#8220;Migliore Prise&#8221; utilizza le foto gi\u00e0 scattate per creare l&#8217;immagine desiderata. Un algoritmo integrato crea un&#8217;immagine combinata da diverse foto in modo che tutti sembrino al meglio. In Google Photos, &#8220;Ritocco Magico&#8221; \u00e8 una nuova esperienza di editing che utilizza l&#8217;IA generativa per rendere le foto scattate pi\u00f9 fedeli all&#8217;atmosfera del momento in cui sono state scattate. \u00c8 possibile ridimensionare e modificare la posizione degli oggetti o utilizzare impostazioni predefinite per mettere in evidenza lo sfondo con pochi tocchi.La &#8220;Gomma Magica Audio&#8221; consente di ridurre facilmente i rumori fastidiosi nei video, come il vento o il frastuono della folla. Questa innovativa funzionalit\u00e0 audio utilizza avanzati modelli di apprendimento automatico per separare i suoni in diverse tracce e controllarne il livello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66282\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro-Cases.jpg\" alt=\"\" width=\"864\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro-Cases.jpg 864w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-8-Pro-Cases-618x515.jpg 618w\" sizes=\"auto, (max-width: 864px) 100vw, 864px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Proteggere le persone e le informazioni personali<\/strong><\/p>\n<p style=\"text-align: justify;\">Google Tensor G3 lavora in tandem con il chip di sicurezza Titan M2 per proteggere le informazioni personali e rendere Pixel pi\u00f9 resistente contro attacchi sofisticati. Su Pixel 8, il riconoscimento facciale \u00e8 ora compatibile con la classe biometrica Android pi\u00f9 elevata, consentendo l&#8217;accesso ad app bancarie e di pagamento come Google Wallet. Con Pixel, gli utenti possono godere di funzionalit\u00e0 e aggiornamenti esclusivi per migliorare costantemente il telefono nel tempo. Per la prima volta, Google offre sette anni di assistenza software per Pixel 8 e Pixel 8 Pro, compresi aggiornamenti del sistema operativo, aggiornamenti di sicurezza e aggiornamenti raggruppati regolarmente.<\/p>\n<p style=\"text-align: justify;\"><strong>Pixel 7a &#8211; ora disponibile anche in Svizzera<\/strong><\/p>\n<p style=\"text-align: justify;\">Ecco il Google Pixel 7a, l&#8217;ultimo smartphone della serie A che offre tutte le funzionalit\u00e0 di Google a un prezzo accessibile. \u00c8 dotato di Google Tensor G2 e Titan M2, che lo rendono pi\u00f9 veloce, efficiente e sicuro. Pixel 7a ha molte delle caratteristiche essenziali degli smartphone premium di Google, ora disponibili per la prima volta in un dispositivo della serie A, come il riconoscimento facciale, 8 GB di RAM, un display Smooth Display fino a 90 Hz e la ricarica wireless.<\/p>\n<figure id=\"attachment_66284\" aria-describedby=\"caption-attachment-66284\" style=\"width: 347px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-66284\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-7a_Sea_DE-1.jpg\" alt=\"\" width=\"347\" height=\"487\"><figcaption id=\"caption-attachment-66284\" class=\"wp-caption-text\">Pixel 7a<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Prezzi e disponibilit\u00e0 in Svizzera<\/strong><\/p>\n<p style=\"text-align: justify;\">Google Pixel 7a, Google Pixel 8 e Google Pixel 8 Pro possono essere preordinati da oggi presso Swisscom, Mobilezone, Digitec e nel Google Store. A partire dal 12 ottobre 2023, gli smartphone saranno ufficialmente disponibili nei negozi in Svizzera.<\/p>\n<table>\n<thead>\n<tr>\n<th>Modell<\/th>\n<th>Colore<\/th>\n<th>Erinnerung<\/th>\n<th>Prezzo CHF<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Google Pixel 7a<\/td>\n<td>Carbone<\/td>\n<td>128 GB<\/td>\n<td>469<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 7a<\/td>\n<td>Neve<\/td>\n<td>128 GB<\/td>\n<td>469<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 7a<\/td>\n<td>Oceano<\/td>\n<td>128 GB<\/td>\n<td>469<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Nero Vulcanico<\/td>\n<td>128 GB<\/td>\n<td>719<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Verde Salvia<\/td>\n<td>128 GB<\/td>\n<td>719<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Rosa<\/td>\n<td>128 GB<\/td>\n<td>719<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Nero Vulcanico<\/td>\n<td>256 GB<\/td>\n<td>779<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Verde Salvia<\/td>\n<td>256 GB<\/td>\n<td>779<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8<\/td>\n<td>Rosa<\/td>\n<td>256 GB<\/td>\n<td>779<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Nero Vulcanico<\/td>\n<td>128 GB<\/td>\n<td>999<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Porcellana<\/td>\n<td>128 GB<\/td>\n<td>999<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Blu Azzurro<\/td>\n<td>128 GB<\/td>\n<td>999<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Nero Vulcanico<\/td>\n<td>256 GB<\/td>\n<td>1.049<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Porcellana<\/td>\n<td>256 GB<\/td>\n<td>1.049<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Blu Azzurro<\/td>\n<td>256 GB<\/td>\n<td>1.049<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel 8 Pro<\/td>\n<td>Nero Vulcanico<\/td>\n<td>512 GB<\/td>\n<td>1.199<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><strong>Pixel Watch 2<\/strong><\/h2>\n<p style=\"text-align: justify;\">Google ha anche presentato il suo ultimo smartwatch, Google Pixel Watch 2. Il Google Pixel Watch 2 \u00e8 dotato di funzionalit\u00e0 di sicurezza, di un design confortevole e di prestazioni potenziate. Gli utenti beneficeranno di un monitoraggio del benessere pi\u00f9 approfondito, di nuovi strumenti per la gestione dello stress e del monitoraggio dell&#8217;attivit\u00e0 fisica ereditati da Fitbit, tra cui lo strumento di monitoraggio della frequenza cardiaca di Google, considerato il pi\u00f9 preciso tra tutti i tracker e gli smartwatch attualmente disponibili.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66285\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band.jpg 720w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Polished-Silver-w_-Porcelain-Band-75x75.jpg 75w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\">Il nuovo Google Pixel Watch 2 (Wifi) sar\u00e0 disponibile a partire dal 12 ottobre 2023 nei negozi in Svizzera e pu\u00f2 essere preordinato da oggi. Il Pixel Watch 2 \u00e8 comodo al polso, con una corona leggermente pi\u00f9 ampia e pulsanti che ne facilitano l&#8217;accesso, per una navigazione fluida. Il suo schermo \u00e8 protetto da un vetro curvo resistente e il suo corpo \u00e8 interamente realizzato in alluminio riciclato. Un coprocessore a basso consumo e le nuove CPU quad-core garantiscono prestazioni superiori e un&#8217;autonomia della batteria di 24 ore (in modalit\u00e0 always-on, che impedisce allo schermo di spegnersi anche in assenza di utilizzo dell&#8217;orologio). In combinazione con una ricarica pi\u00f9 rapida, che porta la batteria al 50% in soli 30 minuti, il Pixel Watch 2 pu\u00f2 gestire le attivit\u00e0 degli utenti giorno e notte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66286\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay.jpg 720w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Woven-Bay-75x75.jpg 75w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Misure precise per un migliore monitoraggio del benessere e dell&#8217;attivit\u00e0 fisica<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Pixel Watch 2 \u00e8 dotato di tre nuovi sensori che consentono agli utenti di migliorare il monitoraggio del loro benessere e li aiutano a effettuare i cambiamenti necessari. Un nuovo sensore di frequenza cardiaca a LED multipli, combinato con un algoritmo di frequenza cardiaca, consente di misurare la frequenza cardiaca con una precisione senza precedenti. Google ha inoltre introdotto la funzione &#8220;Risposte del corpo&#8221; ereditata dal Sense 2, alimentata da un nuovo sensore di attivit\u00e0 elettrodermica continua (cEDA). Questo nuovo sensore pu\u00f2 segnalare possibili segni di stress attraverso un algoritmo di apprendimento automatico che tiene conto della frequenza cardiaca, della variabilit\u00e0 della frequenza cardiaca e della temperatura della pelle. Quando l&#8217;algoritmo rileva indicatori fisici di stress o forti emozioni, la funzione &#8220;Risposte del corpo&#8221; invier\u00e0 una notifica per avvisare gli utenti dello stress potenziale. Successivamente, li incoragger\u00e0 a fare una pausa per riflettere sul proprio stato o ad adottare misure per ridurre il livello di stress, ad esempio attraverso esercizi di respirazione guidata o sessioni di mindfulness. La riflessione su questi momenti, che gli utenti possono consultare nella loro sintesi settimanale dei grafici, pu\u00f2 aiutarli a identificare modelli che possono utilizzare per anticipare lo stress potenziale e pianificare in anticipo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Miglioramenti delle funzionalit\u00e0 fitness Fitbit<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 anche pi\u00f9 facile allenarsi con il Pixel Watch 2. I promemoria automatici di inizio e fine allenamento sono disponibili per sette tipi di esercizi, tra cui la corsa e il ciclismo all&#8217;aperto. Nel frattempo, le nuove funzionalit\u00e0 come il coaching sulla zona di frequenza cardiaca o l&#8217;allenamento del ritmo aiuteranno gli utenti a perseverare nel raggiungere i loro obiettivi durante l&#8217;allenamento. Queste funzioni avvisano gli utenti di cambiamenti nella zona di frequenza cardiaca durante un allenamento HIIT o forniscono feedback in tempo reale sugli obiettivi di ritmo durante una maratona, tramite vibrazione al polso, avvisi vocali o sui nuovi schermi di allenamento completamente rivisti che offrono una migliore leggibilit\u00e0. Tutte le funzionalit\u00e0 benessere e fitness preferite dagli utenti di Fitbit sono ora disponibili anche sul Pixel Watch 2, dalle valutazioni quotidiane della forma fisica al profilo del sonno e al punteggio di sonno, passando per i minuti nella zona attiva, i passi e ben 40 modalit\u00e0 di allenamento.<\/p>\n<p style=\"text-align: justify;\"><strong>Nuove funzionalit\u00e0 di sicurezza per una maggiore tranquillit\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda la sicurezza personale, gli utenti possono godere di una maggiore tranquillit\u00e0 grazie al Pixel Watch 2. Con l&#8217;SOS di Emergenza, il Pixel Watch 2 offre le funzionalit\u00e0 di sicurezza pi\u00f9 proattive di Pixel, come il beacon di soccorso e il controllo della situazione. Il controllo della situazione garantisce che gli utenti non siano mai soli, indipendentemente dalla situazione, anche durante una passeggiata notturna o una corsa al mattino presto. Prima di iniziare, l&#8217;utente pu\u00f2 aprire l&#8217;app Sicurezza personale di Google sul suo orologio, selezionare un&#8217;attivit\u00e0 e avviare un timer in base all&#8217;orario previsto di arrivo a destinazione. \u00c8 quindi possibile selezionare contatti di emergenza da avvisare, informandoli che l&#8217;utente ha avviato un controllo della situazione e fornendo loro informazioni su ci\u00f2 che sta facendo. Se l&#8217;utente non \u00e8 in grado di disattivare il timer una volta scaduto, i contatti di emergenza riceveranno un ulteriore messaggio, compresa la posizione dell&#8217;utente tramite Google Maps, in modo che possano mettersi in contatto con l&#8217;utente o i servizi di emergenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66287\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold.jpg 720w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Metal-Slim-Champagne-Gold-75x75.jpg 75w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Funzionalit\u00e0 di Wear OS 4 e nuove applicazioni migliorate<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Pixel Watch 2 funziona con il nuovo sistema operativo Wear OS 4, che offre agli utenti un&#8217;esperienza pi\u00f9 fluida con il loro orologio, una navigazione pi\u00f9 veloce, intuitiva e una maggiore integrazione con applicazioni come Gmail e Google Calendar. Gli utenti possono ora ascoltare i loro podcast preferiti su YouTube Music o verificare informazioni sui luoghi pi\u00f9 vicini su Google Maps durante la loro corsa. Google ha aggiunto nuove applicazioni da scaricare da Google Play per Wear OS, consentendo agli utenti di fare ancora di pi\u00f9 direttamente dal loro polso. L&#8217;orologio \u00e8 anche facile da abbinare ad altri dispositivi Pixel di un utente. \u00c8 possibile passare l&#8217;audio dall&#8217;orologio alle cuffie e trovare il telefono smarrito grazie alla funzione &#8220;Trova il mio dispositivo&#8221;, il tutto direttamente dal polso. E quando si tratta di passare da un telefono o da un orologio all&#8217;altro, il ripristino dei dati, delle impostazioni e di molto altro dall&#8217;antico dispositivo Wear \u00e8 ancora pi\u00f9 facile.<\/p>\n<p style=\"text-align: justify;\"><strong>Prezzo e disponibilit\u00e0 in Svizzera<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Google Pixel Watch 2 pu\u00f2 essere preordinato da oggi presso Mobilezone, Digitec e Google Store. A partire dal 12 ottobre 2023, il Google Pixel Watch 2 sar\u00e0 ufficialmente disponibile nei negozi in Svizzera.<\/p>\n<table>\n<thead>\n<tr>\n<th>Modell<\/th>\n<th>Colore<\/th>\n<th>Erinnerung<\/th>\n<th>Prezzo CHF<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Google Pixel Watch 2<\/td>\n<td>Nero Mat \/ cinturino Nero Vulcanico<\/td>\n<td>WIFI<\/td>\n<td>379<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel Watch 2<\/td>\n<td>Argento Poli \/ cinturino Blu Azzurro<\/td>\n<td>WIFI<\/td>\n<td>379<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel Watch 2<\/td>\n<td>Argento Poli \/ cinturino Porcellana<\/td>\n<td>WIFI<\/td>\n<td>379<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel Watch 2<\/td>\n<td>Champagne Dorati \/ cinturino Verde Salvia<\/td>\n<td>WIFI<\/td>\n<td>379<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><strong>Pixel Buds Pro<\/strong><\/h2>\n<p style=\"text-align: justify;\">Anche Google Pixel Buds Pro arrivano in Svizzera. Google Pixel Buds Pro sono dotati di funzioni utili e intelligenti. Sono stati progettati per funzionare in perfetta sintonia con l&#8217;intera gamma Pixel di Google. I Google Pixel Buds saranno disponibili a partire dal 12 ottobre 2023 nei negozi in Svizzera e possono essere preordinati da subito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66289\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2.jpg 720w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-2-75x75.jpg 75w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Chiarezza del suono dell&#8217;interlocutore<\/strong><\/p>\n<p style=\"text-align: justify;\">I Pixel Buds Pro integrano l&#8217;IA necessaria per offrire agli utenti un&#8217;eccezionale esperienza audio. Basandosi sulla eccellente qualit\u00e0 delle chiamate dell&#8217;anno scorso, i Pixel Buds Pro supportano ora la funzione di &#8220;Chiarezza del suono dell&#8217;interlocutore&#8221;. Questa funzione riduce i rumori di fondo intorno alla persona dall&#8217;altra parte della chiamata, migliorando cos\u00ec la chiarezza della sua voce in modo che gli utenti possano sentirli ancora pi\u00f9 chiaramente.<\/p>\n<p style=\"text-align: justify;\"><strong>Chiamate in vivavoce<\/strong><\/p>\n<p style=\"text-align: justify;\">Grazie all&#8217;IA, gli utenti non hanno pi\u00f9 bisogno di togliere le cuffie per parlare. Quando l&#8217;utente attiva il rilevamento della conversazione, l&#8217;IA rileva il momento in cui inizia a parlare e reagisce mettendo in pausa la musica e passando alla modalit\u00e0 &#8220;Trasparenza&#8221;, consentendo all&#8217;utente di sentire tutto ci\u00f2 che viene detto intorno a lui. Quando l&#8217;utente smette di parlare, la musica riprende automaticamente e viene attivata la cancellazione attiva del rumore. Gli utenti possono cos\u00ec interagire con il mondo che li circonda e tornare ad ascoltare la loro musica senza distrazioni, il tutto senza dover alzare un dito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66290\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1.jpg 720w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Buds-Pro_Porcelain-1-75x75.jpg 75w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Riduzione della latenza nei giochi<\/strong><\/p>\n<p style=\"text-align: justify;\">I Pixel Buds Pro offrono un&#8217;esperienza di gioco immersiva e dinamica riducendo al minimo la latenza tipica dei giochi Bluetooth. Su Pixel 8 e Pixel 8 Pro, i Pixel Buds Pro riducono il ritardo nella trasmissione dell&#8217;audio dal telefono alle cuffie per i giochi compatibili sullo smartphone Pixel.<\/p>\n<p style=\"text-align: justify;\"><strong>Prezzo e disponibilit\u00e0 in Svizzera<\/strong><\/p>\n<p style=\"text-align: justify;\">I Google Pixel Buds Pro possono essere preordinati da oggi presso Swisscom, Mobilezone, Digitec e Google Store. A partire dal 12 ottobre 2023, saranno ufficialmente disponibili nei negozi in Svizzera.<\/p>\n<table>\n<thead>\n<tr>\n<th>Modell<\/th>\n<th>Colore<\/th>\n<th>Prezzo CHF<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Google Pixel Buds Pro<\/td>\n<td>Carbone<\/td>\n<td>199<\/td>\n<\/tr>\n<tr>\n<td>Google Pixel Buds Pro<\/td>\n<td>Porcellana<\/td>\n<td>199<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Google o tutto o niente, sembra! Dopo anni passati a guardare con interesse, ma da lontano, la gamma di smartphones del gigante statunitense, ora Google si appresta a lanciare un gran numero di devices sul mercato elvetico: smartphones, earbuds e orologi! Pixel 8, Pixel 8 Pro e Pixel 7a In vendita in Svizzera a partire [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":66281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-66277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/de\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera\" \/>\n<meta property=\"og:description\" content=\"Google o tutto o niente, sembra! Dopo anni passati a guardare con interesse, ma da lontano, la gamma di smartphones del gigante statunitense, ora Google si appresta a lanciare un gran numero di devices sul mercato elvetico: smartphones, earbuds e orologi! Pixel 8, Pixel 8 Pro e Pixel 7a In vendita in Svizzera a partire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/de\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-05T07:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"974\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera\",\"datePublished\":\"2023-10-05T07:16:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/\"},\"wordCount\":2292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Pixel-Portfolio_Obsidian-2.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/\",\"name\":\"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Pixel-Portfolio_Obsidian-2.jpg\",\"datePublished\":\"2023-10-05T07:16:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Pixel-Portfolio_Obsidian-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Pixel-Portfolio_Obsidian-2.jpg\",\"width\":974,\"height\":720,\"caption\":\"Pixel Family Bundle H2 Fall 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/de\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google bringt Pixel 8, Pixel Pro 8, Pixel Buds Pro und Pixel Watch 2 in der Schweiz auf den Markt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/de\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/","og_locale":"de_DE","og_type":"article","og_title":"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera","og_description":"Google o tutto o niente, sembra! Dopo anni passati a guardare con interesse, ma da lontano, la gamma di smartphones del gigante statunitense, ora Google si appresta a lanciare un gran numero di devices sul mercato elvetico: smartphones, earbuds e orologi! Pixel 8, Pixel 8 Pro e Pixel 7a In vendita in Svizzera a partire [&hellip;]","og_url":"https:\/\/www.joypad.ch\/de\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2023-10-05T07:16:08+00:00","og_image":[{"width":974,"height":720,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Verfasst von":"Dave","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera","datePublished":"2023-10-05T07:16:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/"},"wordCount":2292,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/","url":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/","name":"Google bringt Pixel 8, Pixel Pro 8, Pixel Buds Pro und Pixel Watch 2 in der Schweiz auf den Markt.","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg","datePublished":"2023-10-05T07:16:08+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/10\/Pixel-Portfolio_Obsidian-2.jpg","width":974,"height":720,"caption":"Pixel Family Bundle H2 Fall 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/google-lancia-pixel-8-pixel-pro-8-pixel-buds-pro-e-pixel-watch-2-in-svizzera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Google lancia Pixel 8, Pixel Pro 8, Pixel Buds Pro e Pixel Watch 2 in Svizzera"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Die Videospiel-, Technologie- und Filmseite f\u00fcr das Tessin und die italienischsprachige Schweiz","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Chefredakteur von Joypad, Sie finden ihn auch in sozialen Netzwerken @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/de\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/66277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/comments?post=66277"}],"version-history":[{"count":2,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/66277\/revisions"}],"predecessor-version":[{"id":66291,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/66277\/revisions\/66291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media\/66281"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media?parent=66277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/categories?post=66277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/tags?post=66277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}