{"id":65555,"date":"2023-06-07T14:17:30","date_gmt":"2023-06-07T12:17:30","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=65555"},"modified":"2023-06-07T14:17:30","modified_gmt":"2023-06-07T12:17:30","slug":"die-neuesten-innovationen-von-logitech-im-bereich-produktivitatsperipheriegerate","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/de\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/","title":{"rendered":"Logitechs neueste Produktivit\u00e4tsperipherieger\u00e4te"},"content":{"rendered":"<p style=\"text-align: justify;\">Logitech ha annunciato il lancio di MX Keys S Combo, della tastiera MX Keys S e del mouse MX Anywhere 3S, che si aggiungono alla popolare serie Premium Master, sviluppata in collaborazione con sviluppatori di software e creativi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-64728\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo.png\" alt=\"\" width=\"280\" height=\"85\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo.png 5000w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo-790x240.png 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo-1024x311.png 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo-1536x467.png 1536w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2022\/12\/Logitech_logo-2048x623.png 2048w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/p>\n<p style=\"text-align: justify;\">Grazie alle Smart Actions, una nuova funzione del software Logi Options+, gli utenti possono aumentare la produttivit\u00e0 e trovare il proprio &#8220;flusso&#8221; personale con i nuovi prodotti Logitech.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>MX Keys S Combo<\/strong><br \/>\nLa MX Keys S Combo comprende la nuova tastiera MX Keys S, il popolare mouse MX Master 3S e il comodo MX Palm Rest. Questo duo \u00e8 perfetto per lavorare in modo rapido e preciso ed \u00e8 ideale per professionisti esperti che desiderano massima creativit\u00e0 e produttivit\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65559\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_PNG-MX-Keys-S-Combo-C-BTY2-Graphite-US.png\" alt=\"\" width=\"719\" height=\"405\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_PNG-MX-Keys-S-Combo-C-BTY2-Graphite-US.png 1363w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_PNG-MX-Keys-S-Combo-C-BTY2-Graphite-US-790x445.png 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_PNG-MX-Keys-S-Combo-C-BTY2-Graphite-US-1024x577.png 1024w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/p>\n<p>L&#8217;illuminazione intelligente e i tasti personalizzabili della tastiera si combinano con i clic silenziosi, la scorrimento rapido e preciso e il sensore da 8K DPI del mouse, che funziona anche su superfici in vetro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65558\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-BOB-COMBO-A-LIFE-Pale-Grey.jpg\" alt=\"\" width=\"841\" height=\"501\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-BOB-COMBO-A-LIFE-Pale-Grey.jpg 1289w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-BOB-COMBO-A-LIFE-Pale-Grey-790x471.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-BOB-COMBO-A-LIFE-Pale-Grey-1024x610.jpg 1024w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>MX Keys S<\/strong><br \/>\nLa tastiera wireless MX Keys S di Logitech offre una piacevole esperienza di digitazione con tasti che si adattano alle punte delle dita, consentendo agli utenti di digitare velocemente, fluidamente e comodamente. L&#8217;illuminazione intelligente rileva la vicinanza delle mani alla tastiera e si adatta automaticamente alle condizioni di illuminazione della stanza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65561\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-AMAZON-Pale-Grey-US-INTL-1.jpg\" alt=\"\" width=\"693\" height=\"274\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-AMAZON-Pale-Grey-US-INTL-1.jpg 1364w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-AMAZON-Pale-Grey-US-INTL-1-790x313.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-AMAZON-Pale-Grey-US-INTL-1-1024x405.jpg 1024w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Inoltre, gli utenti possono personalizzare l&#8217;illuminazione tramite l&#8217;app Logi Options+. La MX Keys S \u00e8 disponibile nei colori grafite e grigio pallido e presenta un layout migliorato con tre nuovi tasti per massimizzare la produttivit\u00e0 e la collaborazione: Dictate, Microfono, muto\/ripristina audio e il menu Emoji.<\/p>\n<p style=\"text-align: justify;\"><strong>MX Anywhere 3S<\/strong><br \/>\nIl mouse compatto wireless MX Anywhere 3S di Logitech, il pi\u00f9 avanzato finora, \u00e8 particolarmente adatto a utenti che apprezzano prestazioni, portabilit\u00e0 e comfort. La rotellina elettromagnetica MagSpeed garantisce uno scorrimento rapido, preciso e quasi silenzioso, mentre la tecnologia Quiet Click rende il MX Anywhere 3S molto pi\u00f9 silenzioso rispetto al suo predecessore (MX Anywhere 3). Il mouse dispone di un sensore ottico da 8.000 DPI che funziona su praticamente tutte le superfici, compreso il vetro, consentendo agli utenti di essere produttivi ovunque.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65564\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_JPG-MX-Anywhere-3S-3QTR-Front-Pale-Grey.jpg\" alt=\"\" width=\"658\" height=\"370\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_JPG-MX-Anywhere-3S-3QTR-Front-Pale-Grey.jpg 1365w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_JPG-MX-Anywhere-3S-3QTR-Front-Pale-Grey-790x444.jpg 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/High_Resolution_JPG-MX-Anywhere-3S-3QTR-Front-Pale-Grey-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Preis und Verf\u00fcgbarkeit<\/strong><br \/>\nLa MX Keys S, la MX Keys S Combo e la MX Anywhere 3S saranno disponibili da giugno 2023 su logitech.com e presso i rivenditori. Il prezzo consigliato per la MX Keys S \u00e8 di CHF 129, per la MX Keys S Combo CHF 229 e per la MX Anywhere 3S CHF 119.<\/p>\n<p style=\"text-align: justify;\">L&#8217;app Logi Options+ \u00e8 disponibile gratuitamente per il download su logi.com\/optionsplus.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65565\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\" alt=\"\" width=\"1151\" height=\"768\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg 1151w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09-772x515.jpg 772w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09-1024x683.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09-333x222.jpg 333w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09-240x160.jpg 240w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09-360x240.jpg 360w\" sizes=\"auto, (max-width: 1151px) 100vw, 1151px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Logitech ha annunciato il lancio di MX Keys S Combo, della tastiera MX Keys S e del mouse MX Anywhere 3S, che si aggiungono alla popolare serie Premium Master, sviluppata in collaborazione con sviluppatori di software e creativi. Grazie alle Smart Actions, una nuova funzione del software Logi Options+, gli utenti possono aumentare la produttivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":65565,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-65555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/de\/die-neuesten-innovationen-von-logitech-im-bereich-produktivitatsperipheriegerate\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Logitech ha annunciato il lancio di MX Keys S Combo, della tastiera MX Keys S e del mouse MX Anywhere 3S, che si aggiungono alla popolare serie Premium Master, sviluppata in collaborazione con sviluppatori di software e creativi. Grazie alle Smart Actions, una nuova funzione del software Logi Options+, gli utenti possono aumentare la produttivit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/de\/die-neuesten-innovationen-von-logitech-im-bereich-produktivitatsperipheriegerate\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-07T12:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1151\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0\",\"datePublished\":\"2023-06-07T12:17:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/\",\"name\":\"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\",\"datePublished\":\"2023-06-07T12:17:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg\",\"width\":1151,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/de\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logitechs neueste Produktivit\u00e4tsperipherieger\u00e4te","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/de\/die-neuesten-innovationen-von-logitech-im-bereich-produktivitatsperipheriegerate\/","og_locale":"de_DE","og_type":"article","og_title":"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0","og_description":"Logitech ha annunciato il lancio di MX Keys S Combo, della tastiera MX Keys S e del mouse MX Anywhere 3S, che si aggiungono alla popolare serie Premium Master, sviluppata in collaborazione con sviluppatori di software e creativi. Grazie alle Smart Actions, una nuova funzione del software Logi Options+, gli utenti possono aumentare la produttivit\u00e0 [&hellip;]","og_url":"https:\/\/www.joypad.ch\/de\/die-neuesten-innovationen-von-logitech-im-bereich-produktivitatsperipheriegerate\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2023-06-07T12:17:30+00:00","og_image":[{"width":1151,"height":768,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Verfasst von":"Dave","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0","datePublished":"2023-06-07T12:17:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/","url":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/","name":"Logitechs neueste Produktivit\u00e4tsperipherieger\u00e4te","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg","datePublished":"2023-06-07T12:17:30+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/06\/Low_Resolution_JPG-MX-Keys-S-LIFE-Graphite-09.jpg","width":1151,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/le-novita-di-logitech-in-campo-periferiche-per-la-produttivita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Le novit\u00e0 di Logitech in campo periferiche per la produttivit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Die Videospiel-, Technologie- und Filmseite f\u00fcr das Tessin und die italienischsprachige Schweiz","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Chefredakteur von Joypad, Sie finden ihn auch in sozialen Netzwerken @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/de\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/comments?post=65555"}],"version-history":[{"count":2,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65555\/revisions"}],"predecessor-version":[{"id":65567,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65555\/revisions\/65567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media\/65565"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media?parent=65555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/categories?post=65555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/tags?post=65555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}