{"id":65234,"date":"2023-03-03T14:22:21","date_gmt":"2023-03-03T13:22:21","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=65234"},"modified":"2023-03-03T14:22:21","modified_gmt":"2023-03-03T13:22:21","slug":"sony-annuncia-due-nuove-cuffie","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/de\/sony-annuncia-due-nuove-cuffie\/","title":{"rendered":"Sony k\u00fcndigt zwei neue Kopfh\u00f6rer an"},"content":{"rendered":"<p style=\"text-align: justify;\">Sony ha annunciato due nuove cuffie &#8211; i modelli WH-CH720N e WH-CH520 &#8211; con la scelta tra una versione on-ear e una over-ear. Entrambi i modelli sono senza fili e dispongono di numerose tecnologie audio Sony.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-42202\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/03\/Sony_logo.svg_.png\" alt=\"\" width=\"272\" height=\"49\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/03\/Sony_logo.svg_.png 2000w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/03\/Sony_logo.svg_-790x142.png 790w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2017\/03\/Sony_logo.svg_-1024x184.png 1024w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Le cuffie over-ear senza fili WH-CH720N sono dotate della tecnologia dual noise sensor e del chip di processore integrato V1 di Sony per minimizzare affidabilmente i rumori fastidiosi. Grazie al suo design leggero e alla durata della batteria fino a 35 ore1, gli utenti possono godersi la loro musica a lungo e senza disturbi. Le cuffie on-ear senza fili WH-CH520 sono dotate di una durata della batteria fino a 50 ore, comfort di utilizzo per tutto il giorno e una qualit\u00e0 di chiamata ancora migliore per tutte le esigenze quotidiane. Con quattro diverse opzioni di colore &#8211; nero, blu, bianco e beige &#8211; soddisfa ogni gusto.<\/p>\n<p style=\"text-align: justify;\">Entrambi i modelli sono dotati della tecnologia Digital Sound Enhancement Engine (DSEE) di Sony per rendere la musica come pensata dagli artisti. E grazie alla connessione multipunto, le due cuffie possono passare senza soluzione di continuit\u00e0 tra due dispositivi accoppiati.<\/p>\n<p style=\"text-align: justify;\"><strong>WH-CH720N<\/strong><br \/>\nIl WH-CH720N elimina affidabilmente il rumore dei rumori di fondo, come il rumore degli aerei o il chiacchiericcio del caff\u00e8. Con l&#8217;efficace cancellazione del rumore di Sony, basata sul processore integrato V1 e sulla tecnologia dual noise sensor, il WH-CH720N offre un&#8217;esperienza musicale pura. Il processore integrato V1 aiuta a ridurre i rumori ambientali e consente un noise cancelling ancora pi\u00f9 efficace grazie alla sua bassa latenza di elaborazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65235\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4.jpg\" alt=\"\" width=\"768\" height=\"768\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4.jpg 768w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-4-75x75.jpg 75w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p style=\"text-align: justify;\">Inoltre, il WH-CH720N dispone di due microfoni in ogni cuffia che, in combinazione con la tecnologia dual noise sensor, rilevano i rumori ambientali per sopprimere efficacemente i rumori fastidiosi. Il risultato \u00e8 un&#8217;esperienza musicale pura. Inoltre, l&#8217;app Sony | Headphones Connect d\u00e0 agli utenti la possibilit\u00e0 di regolare il volume dei rumori ambientali in 20 fasi per adattarli perfettamente a qualsiasi situazione in movimento. Con il WH-CH720N, la musica non deve pi\u00f9 fare pause forzate. Le cuffie over-ear sono ergonomicamente sagomate e quindi sempre confortevoli anche per un uso prolungato. Con un peso di soli 192 grammi, il WH-CH720N \u00e8 la cuffia wireless con cancellazione del rumore pi\u00f9 leggera di Sony con design overhead. I materiali utilizzati &#8211; ecopelle e uretano &#8211; contribuiscono al comfort eccellente, cos\u00ec come la struttura e le dimensioni ottimali dei padiglioni auricolari. E anche la batteria \u00e8 progettata per un funzionamento duraturo: con la cancellazione del rumore attivata, dura fino a 35 ore.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65236\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13.jpg\" alt=\"\" width=\"619\" height=\"619\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13.jpg 768w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony-13-75x75.jpg 75w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/p>\n<div class=\"w-[30px] flex flex-col relative items-end\" style=\"text-align: justify;\">\n<div class=\"relative h-[30px] w-[30px] p-1 rounded-sm text-white flex items-center justify-center\"><strong>WH-CH520<br \/>\n<\/strong>Il modello WH-CH520 \u00e8 completamente attrezzato per la vita quotidiana. Grazie a un&#8217;autonomia della batteria fino a 50 ore, gli amanti della musica possono godersi a lungo le loro canzoni preferite senza dover pensare alla ricarica. Inoltre, queste cuffie over-ear offrono sempre una buona vestibilit\u00e0 e un elevato comfort grazie alla fascia regolabile imbottita, ai morbidi padiglioni auricolari e alla leggerezza della struttura, anche durante l&#8217;ascolto prolungato.<\/div>\n<div>&nbsp;<\/div>\n<\/div>\n<div>&nbsp;<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65239\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5.jpg\" alt=\"\" width=\"603\" height=\"603\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5.jpg 768w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-5-75x75.jpg 75w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/><\/div>\n<div>&nbsp;<\/div>\n<div class=\"w-[30px] flex flex-col relative items-end\" style=\"text-align: justify;\">\n<div class=\"relative h-[30px] w-[30px] p-1 rounded-sm text-white flex items-center justify-center\">Digital Sound Enhancement Engine (DSEE) garantisce un suono naturale, cristallino e bilanciato alle cuffie WH-CH720N e WH-CH520, proprio come gli artisti e i produttori avevano previsto. Quando la musica viene compressa, le frequenze alte vengono perse, le quali conferiscono dettagli e pienezza al suono. Il Digital Sound Enhancement Engine di Sony ripristina queste frequenze, fornendo cos\u00ec un suono di alta qualit\u00e0 che si avvicina molto all&#8217;originale. Il processore integrato V1 nel WH-CH720N riduce al minimo le distorsioni per garantire un&#8217;esperienza di ascolto autentica. L&#8217;equilibrio delle frequenze dal basso all&#8217;alto e la riproduzione vocale naturale e chiara sono le caratteristiche del suono.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65240\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20.jpg\" alt=\"\" width=\"667\" height=\"667\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20.jpg 768w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-515x515.jpg 515w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-150x150.jpg 150w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-200x200.jpg 200w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-166x166.jpg 166w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-118x118.jpg 118w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-55x55.jpg 55w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH520_von_Sony-20-75x75.jpg 75w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div>\n<\/div>\n<div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-4 whitespace-pre-wrap\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p style=\"text-align: justify;\"><strong>Prezzo consigliato e disponibilit\u00e0<\/strong><br \/>\nSony WH-CH720N in nero, blu e bianco: CHF 149 Disponibilit\u00e0: a partire dalla fine di febbraio 2023<br \/>\nSony WH-CH520 in nero, blu, bianco e beige: CHF 69 Disponibilit\u00e0: a partire dalla fine di febbraio 2023<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sony ha annunciato due nuove cuffie &#8211; i modelli WH-CH720N e WH-CH520 &#8211; con la scelta tra una versione on-ear e una over-ear. Entrambi i modelli sono senza fili e dispongono di numerose tecnologie audio Sony. &nbsp; &nbsp; Le cuffie over-ear senza fili WH-CH720N sono dotate della tecnologia dual noise sensor e del chip di [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":65241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[],"class_list":["post-65234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sony annuncia due nuove cuffie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/de\/sony-annuncia-due-nuove-cuffie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sony annuncia due nuove cuffie\" \/>\n<meta property=\"og:description\" content=\"Sony ha annunciato due nuove cuffie &#8211; i modelli WH-CH720N e WH-CH520 &#8211; con la scelta tra una versione on-ear e una over-ear. Entrambi i modelli sono senza fili e dispongono di numerose tecnologie audio Sony. &nbsp; &nbsp; Le cuffie over-ear senza fili WH-CH720N sono dotate della tecnologia dual noise sensor e del chip di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/de\/sony-annuncia-due-nuove-cuffie\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T13:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1151\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Sony annuncia due nuove cuffie\",\"datePublished\":\"2023-03-03T13:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/\"},\"wordCount\":634,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WH-CH720N_von_Sony_Lifestyle-1.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/\",\"name\":\"Sony annuncia due nuove cuffie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WH-CH720N_von_Sony_Lifestyle-1.jpg\",\"datePublished\":\"2023-03-03T13:22:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WH-CH720N_von_Sony_Lifestyle-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WH-CH720N_von_Sony_Lifestyle-1.jpg\",\"width\":1151,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/sony-annuncia-due-nuove-cuffie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sony annuncia due nuove cuffie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/de\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sony k\u00fcndigt zwei neue Kopfh\u00f6rer an","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/de\/sony-annuncia-due-nuove-cuffie\/","og_locale":"de_DE","og_type":"article","og_title":"Sony annuncia due nuove cuffie","og_description":"Sony ha annunciato due nuove cuffie &#8211; i modelli WH-CH720N e WH-CH520 &#8211; con la scelta tra una versione on-ear e una over-ear. Entrambi i modelli sono senza fili e dispongono di numerose tecnologie audio Sony. &nbsp; &nbsp; Le cuffie over-ear senza fili WH-CH720N sono dotate della tecnologia dual noise sensor e del chip di [&hellip;]","og_url":"https:\/\/www.joypad.ch\/de\/sony-annuncia-due-nuove-cuffie\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2023-03-03T13:22:21+00:00","og_image":[{"width":1151,"height":768,"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg","type":"image\/jpeg"}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Verfasst von":"Dave","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Sony annuncia due nuove cuffie","datePublished":"2023-03-03T13:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/"},"wordCount":634,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/","url":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/","name":"Sony k\u00fcndigt zwei neue Kopfh\u00f6rer an","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg","datePublished":"2023-03-03T13:22:21+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2023\/03\/WH-CH720N_von_Sony_Lifestyle-1.jpg","width":1151,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/sony-annuncia-due-nuove-cuffie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.joypad.ch\/news\/"},{"@type":"ListItem","position":3,"name":"Sony annuncia due nuove cuffie"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Die Videospiel-, Technologie- und Filmseite f\u00fcr das Tessin und die italienischsprachige Schweiz","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Chefredakteur von Joypad, Sie finden ihn auch in sozialen Netzwerken @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/de\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/comments?post=65234"}],"version-history":[{"count":1,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65234\/revisions"}],"predecessor-version":[{"id":65242,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/65234\/revisions\/65242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media\/65241"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media?parent=65234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/categories?post=65234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/tags?post=65234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}