{"id":15961,"date":"2014-02-11T13:11:13","date_gmt":"2014-02-11T11:11:13","guid":{"rendered":"https:\/\/www.joypad.ch\/?p=15961"},"modified":"2014-02-11T13:19:22","modified_gmt":"2014-02-11T11:19:22","slug":"tomb-raider-definitive-edition","status":"publish","type":"post","link":"https:\/\/www.joypad.ch\/de\/tomb-raider-definitive-edition\/","title":{"rendered":"Tomb Raider Definitive Edition"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Lara Croft<\/strong> approda su nextgen! Pi\u00f9 inesperta, meno ganassa e decisamente foderata di kevlar, la bella razziatrice di tombe \u00e8 pronta a farvi battere il cuore nel reboot di questa storia serie inizialmente uscito su PC, Playstation 3 e Xbox 360. In una mossa piuttosto discuribile, Crystal Dynamics ha deciso di proporre la Definitive Edition su <strong>Xbox One<\/strong> e <strong>Playstation 4<\/strong>. Cosa c\u2019\u00e8 oltre all\u2019upgrade grafico?<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15962\" alt=\"tomb raider definitive\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png\" width=\"600\" height=\"155\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png 600w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive-300x77.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><strong>Odio le tombe!<\/strong><\/h2>\n<p style=\"text-align: justify;\">In Tomb Raider impersoniamo Lara Croft, giovanissima archeologa\/avventuriera alle prime armi. <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-15965\" alt=\"trdef (3)\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-3-1024x576.jpg\" width=\"341\" height=\"191\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-3-1024x576.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-3-300x168.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-3.jpg 1920w\" sizes=\"auto, (max-width: 341px) 100vw, 341px\" \/>La troviamo alla ricerca dell\u2019<strong>impero degli Yamatai<\/strong>, antico dominio della potentissima regina Himiko, in compagnia di un eterogeneo gruppo di persone, tra cui l\u2019amica Sam. Quella che sembra una semplice spedizione archeologica a bordo di una nave si trasforma subito in incubo quando, <strong>complice una terribile tempesta<\/strong>, la nave di Lara fa naufragio. Nonostante le condizioni metereologiche precarie, tutto il gruppo riesce ad approdare su un\u2019isola misteriosa, sebbene separati gli uni dagli altri. Per peggiorare ancora di pi\u00f9 le cose, la povera Lara finir\u00e0 rapita e appesa a testa in gi\u00f9 in una grotta piena di teschi e cadaveri in vari stati di decomposizione. E proprio in questa caverna inizia il viaggio dell\u2019avventuriera britannica,<strong> la quale cercher\u00e0 di salvare se stessa e i propri amici<\/strong>, senza contare il processo che la far\u00e0 diventare una <strong>vera predatrice di tombe<\/strong>!<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15968\" alt=\"trdef (1)\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-1.jpg\" width=\"960\" height=\"540\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-1.jpg 960w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-1-300x168.jpg 300w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"text-align: justify;\">Questo nuovo Tomb Raider insomma ci vede ai comandi di una <strong>Lara alle prime armi<\/strong>, insicura e spaventata. Spesso e volentieri proveremo quasi pena per lei, visto l\u2019enorme numero di ferite e cadute che dovr\u00e0 subire. Vederne l\u2019espressione mentre, mezza affogata sotto terra, cerca una via di fuga dal buio opprimente, ci fa venire voglia di prendercene cura. E lo faremo, aiutandola a sopravvivere e ad apprendere le tecniche di sopravvivenza. Il gioco infatti implementa <strong>un sistema di punti d\u2019esperienza<\/strong> che ci permettono di migliorare le nostre capacit\u00e0 in diversi campi, quali la sopravvivenza oppure le tecniche di combattimento. Per occuparci di questi elementi e upgrade degli armamenti, dobbiamo servirci dei fuochi da campo. Si tratta di zone speciali del gioco in cui potremo salvare la partita, migliorare armi e noi stessi e viaggiare istantaneamente da un punto all\u2019altro dell\u2019isola. Sebbene il nuovo Tomb Raider <strong>non sia un gioco free roaming allo stato puro<\/strong>, abbiamo spesso e volentieri totale libert\u00e0 di movimento per l\u2019isola. <img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-15970\" alt=\"trdef (7)\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-7.jpg\" width=\"371\" height=\"246\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-7.jpg 620w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-7-300x199.jpg 300w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/>Non si tratta di una libert\u00e0 che ci distrae dai nostri scopi (come visto in altri titoli), ma un piacevole modo per affrontare l\u2019avventura. Spesso e volentieri infatti possiamo <strong>sfruttare strade secondarie<\/strong> e meno evidenti per evitare i nemici oppure per tendere loro delle imboscate. La nuova Lara infatti predilige un approccio furtivo, basato su <strong>arco e frecce<\/strong>. Quest\u2019arma assume un importanza primaria dal momento che non solo serve ad eliminare i nemici in modo silenzioso e discreto, ma anche a far esplodere degli oggetti (tramite le frecce infuocate) e a creare dei ponti, lanciando frecce collegate a funi. Non mancano bene inteso le armi pi\u00f9 tradizionali, dal fucile a pompa al fucile d\u2019assalto, per i momenti in cui non siete stati discreti a sufficienza oppure durante delle sorta di boss fight. Oltre alla storia principale, ci sono <strong>varie attivit\u00e0 in cui potrete cimentarvi<\/strong>. Per esempio potete cacciare oppure darvi all\u2019esplorazione. Esistono svariate tombe secondarie che vanno trovate sulla mappa. In queste tombe saremo sempre posti di fronte ad un diverso tipo di enigma, il quale andr\u00e0 risolto grazie ad un po\u2019 di intuito. Nella maggior parte dei casi qualche tentativo baster\u00e0 a capirne il meccanismo, mentre in altre dovrete dare sfoggio a un po\u2019 di pensiero creativo! <strong>Davvero niente male<\/strong>!<\/p>\n<h2 style=\"text-align: justify;\"><strong>Eye candy<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il<strong> level design e la grafica sono sbalorditive<\/strong>. Il motore di gioco creato da Crystal Dynamics \u00e8 meraviglioso, con una profondit\u00e0 di campo invidiabile e una marea di effetti speciali. Tomb Raider \u00e8 semplicemente bello da guardare, con una moltitudine di effetti di luce e vari effetti di post processing. <strong>L\u2019acqua poi \u00e8 onnipresente<\/strong>, con fiumi impetuosi, pozze, l\u2019oceano, ruscelli e tempeste. Insomma, una vera isola pluviale che non vede l\u2019ora di essere scoperta. <strong>La Definitive Edition introduce<\/strong>, rispetto alla controparte oldgen, <strong>alcune cose molto interessanti<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15973\" alt=\"trdef (2)\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-2-1024x422.jpg\" width=\"729\" height=\"300\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-2-1024x422.jpg 1024w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-2-300x123.jpg 300w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-2.jpg 1038w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/><\/p>\n<p style=\"text-align: justify;\">Per prima cosa il modello di Lara \u00e8 stato completamente rifatto. Grazie a tecniche particoalari, quali <strong>TressFX<\/strong> e <strong>sub-surface scattering<\/strong>, essa \u00e8 molto pi\u00f9 realistica. TressFX \u00e8 una tecnologia che permette di animare i capelli in modo naturale, animandoli singolarmente e dando loro delle movenze pi\u00f9 vere. I capelli di Lara reagiranno dunque a vento e movimento e si muoveranno realisticamente scivolando sulle spalle (tranne quando \u00e8 appesa a testa in gi\u00f9, inspiegabilmente continueranno a penzolare verso l\u2019alto\u2026 al contrario insomma). Il sub-surface scattering invece permette alla<strong> luce di rimbalzare sugli strati della pelle di Lara<\/strong> e di spandersi sia verso l\u2019esterno, sia verso l\u2019interno. Il risultato di una tecnica che sembra un po\u2019 astrusa \u00e8 che gli effetti di luce sulla pelle della protagonista sono davvero <strong>molto pi\u00f9 realistici e riusciti rispetto al passato<\/strong>. Sfortunatamente non sembra che gli altri personaggi del gioco abbiano beneficiato dello stesso grado di attenzione dal momento che mantengono lo stesso aspetto che avevano nella old gen. Certo, le texture sono 4 volte pi\u00f9 definite, ma niente TressFX o sub-surface scattering per quanto ci sembra. Il <strong>mondo di gioco \u00e8 stato notevolmente perfezionato<\/strong>: adesso vedremo molta pi\u00f9 animazione e un campo pi\u00f9 lungo. <img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-15977\" alt=\"trdef (6)\" src=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-6.jpg\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-6.jpg 620w, https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/trdef-6-300x199.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>Nella nuova versione dell\u2019isola maledetta vedremo gli alberi muoversi dolcemente al vento, gli arbusti reagire al nostro passaggio, effetti di fumo pi\u00f9 realistici e un gran numero di effetti particellari. In particolare nei livelli con incendi, vedremo un gran numero di tizzoni ardenti volare nel cielo. Effetti davvero molto riusciti, non c\u2019\u00e8 che dire, e che ci danno uno scorcio di cosa sar\u00e0 la vera nextgen. <strong>Tutto questo ben degli dei grafico per\u00f2 era gi\u00e0 disponibile su PC un anno fa<\/strong>, in particolar modo il TressFX. Tomb Raider Definitive Edition non \u00e8 che offra poi questo enorme vantaggio rispetto al gioco \u2013 per altro ottimo \u2013 uscito lo scorso anno. Intendiamoci, il sottoscritto si \u00e8 ampiamente goduto la seconda partita fatta ed ha particolarmente apprezzato le migliorie che rendono questa versione la vera versione definitiva (come non ha smesso di ripeterci fino alla nausea il team di sviluppo). Tuttavia,<strong> se avete gi\u00e0 giocato su PS3, Xbox 360 e PC<\/strong>, non ha molto senso che acquistiate questa versione. I contenuti sono i medesimi e il gioco non offre nulla di pi\u00f9 se non un eye candy migliorato. Bello da vedere, ma immutato nella sostanza. Per quanto riguarda le musiche, esse non sono affatto memorabili ma riescono comunque a sottolineare piuttosto bene l\u2019azione. Il <strong>doppiaggio italiano \u00e8 di tutto rispetto<\/strong>, con i personaggi piuttosto ben caratterizzati e una dizione credibile.<\/p>\n<p style=\"text-align: justify;\">Tomb Raider offre anche una <strong>modalit\u00e0 multiplayer<\/strong>, in cui potrete sfidare persone online alla sopravvivenza. Si tratta di una modalit\u00e0 inserita, a mio avviso, perch\u00e9 ogni gioco al giorno d\u2019oggi deve avere una modalit\u00e0 online. Graficamente scarsa e con modalit\u00e0 piuttosto classiche, decisamente \u00e8 stato implementato per fare presenza.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Valutazione Definitiva<\/strong><\/h2>\n<p style=\"text-align: justify;\">Insomma <strong>questo gioco \u00e8 ben riuscito<\/strong>. Forse la storia \u00e8 troppo incentrata sull\u2019azione pura e non ottiene quell\u2019effetto cinematografico che tanto bene ha caratterizzato fin qui la serie Uncharted su Playstation 3. I difetti comunque non sono molti e fanno di questa nuova avventura di Lara Croft un buon gioco, degno di essere provato dagli amanti del genere. <strong>Cos\u00ec come ci ha convinto lo scorso anno, ci ha convinto di nuovo<\/strong>. Ma tenete ben presente che il gioco offre ben poco in pi\u00f9 rispetto al passato. Da acquistare solo se avete una console nextgen e non avete avuto la possibilit\u00e0 di fare visita a Lara Croft lo scorso anno!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Vi lasciamo con un trailer comparativo realizzato da IGN sulle differenze tra le generazioni del gioco<\/p>\n<p style=\"text-align: justify;\">\n<div style=\"text-align:center\">\n[youtube link=&#8221;http:\/\/youtu.be\/7NUX2rG_u8w&#8221; width=&#8221;590&#8243; height=&#8221;315&#8243;]\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lara Croft approda su nextgen! Pi\u00f9 inesperta, meno ganassa e decisamente foderata di kevlar, la bella razziatrice di tombe \u00e8 pronta a farvi battere il cuore nel reboot di questa storia serie inizialmente uscito su PC, Playstation 3 e Xbox 360. In una mossa piuttosto discuribile, Crystal Dynamics ha deciso di proporre la Definitive Edition [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-15961","post","type-post","status-publish","format-standard","hentry","category-recensioni"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tomb Raider Definitive Edition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joypad.ch\/de\/tomb-raider-definitive-edition\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tomb Raider Definitive Edition\" \/>\n<meta property=\"og:description\" content=\"Lara Croft approda su nextgen! Pi\u00f9 inesperta, meno ganassa e decisamente foderata di kevlar, la bella razziatrice di tombe \u00e8 pronta a farvi battere il cuore nel reboot di questa storia serie inizialmente uscito su PC, Playstation 3 e Xbox 360. In una mossa piuttosto discuribile, Crystal Dynamics ha deciso di proporre la Definitive Edition [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joypad.ch\/de\/tomb-raider-definitive-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Joypad.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/www.joypad.ch\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-11T11:11:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-11T11:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:site\" content=\"@JoypadCH\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/\"},\"author\":{\"name\":\"Dave\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\"},\"headline\":\"Tomb Raider Definitive Edition\",\"datePublished\":\"2014-02-11T11:11:13+00:00\",\"dateModified\":\"2014-02-11T11:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/\"},\"wordCount\":1305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/tomb-raider-definitive.png\",\"articleSection\":[\"Recensione\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/\",\"name\":\"Tomb Raider Definitive Edition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/tomb-raider-definitive.png\",\"datePublished\":\"2014-02-11T11:11:13+00:00\",\"dateModified\":\"2014-02-11T11:19:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/tomb-raider-definitive.png\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/tomb-raider-definitive.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/tomb-raider-definitive-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joypad.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tomb Raider Definitive Edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"name\":\"Joypad.ch\",\"description\":\"Il sito di videogiochi, tecnologia e film per il Ticino e la Svizzera di lingua italiana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joypad.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#organization\",\"name\":\"Joypad.ch\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joypad.ch\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo_def_bn.jpg\",\"width\":6671,\"height\":902,\"caption\":\"Joypad.ch\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.joypad.ch\",\"https:\\\/\\\/x.com\\\/JoypadCH\",\"https:\\\/\\\/www.instagram.com\\\/joypadch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/JoypadCH\",\"https:\\\/\\\/www.tiktok.com\\\/@mrpipistro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joypad.ch\\\/#\\\/schema\\\/person\\\/d7375963dc860aac116f9733865d5b74\",\"name\":\"Dave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g\",\"caption\":\"Dave\"},\"description\":\"Editor in Chief di Joypad, lo trovate anche sui social @MrPipistro\",\"sameAs\":[\"https:\\\/\\\/www.joypad.ch\",\"www.instagram.com\\\/joypadch\",\"www.youtube.com\\\/@JoypadCH\"],\"url\":\"https:\\\/\\\/www.joypad.ch\\\/de\\\/author\\\/dave\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tomb Raider Definitive Edition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joypad.ch\/de\/tomb-raider-definitive-edition\/","og_locale":"de_DE","og_type":"article","og_title":"Tomb Raider Definitive Edition","og_description":"Lara Croft approda su nextgen! Pi\u00f9 inesperta, meno ganassa e decisamente foderata di kevlar, la bella razziatrice di tombe \u00e8 pronta a farvi battere il cuore nel reboot di questa storia serie inizialmente uscito su PC, Playstation 3 e Xbox 360. In una mossa piuttosto discuribile, Crystal Dynamics ha deciso di proporre la Definitive Edition [&hellip;]","og_url":"https:\/\/www.joypad.ch\/de\/tomb-raider-definitive-edition\/","og_site_name":"Joypad.ch","article_publisher":"https:\/\/www.facebook.com\/www.joypad.ch","article_published_time":"2014-02-11T11:11:13+00:00","article_modified_time":"2014-02-11T11:19:22+00:00","og_image":[{"url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png","type":"","width":"","height":""}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@JoypadCH","twitter_site":"@JoypadCH","twitter_misc":{"Verfasst von":"Dave","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#article","isPartOf":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/"},"author":{"name":"Dave","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74"},"headline":"Tomb Raider Definitive Edition","datePublished":"2014-02-11T11:11:13+00:00","dateModified":"2014-02-11T11:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/"},"wordCount":1305,"commentCount":0,"publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"image":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png","articleSection":["Recensione"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/","url":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/","name":"Tomb Raider Definitive Edition","isPartOf":{"@id":"https:\/\/www.joypad.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#primaryimage"},"image":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png","datePublished":"2014-02-11T11:11:13+00:00","dateModified":"2014-02-11T11:19:22+00:00","breadcrumb":{"@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#primaryimage","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2014\/02\/tomb-raider-definitive.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joypad.ch\/tomb-raider-definitive-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joypad.ch\/"},{"@type":"ListItem","position":2,"name":"Tomb Raider Definitive Edition"}]},{"@type":"WebSite","@id":"https:\/\/www.joypad.ch\/#website","url":"https:\/\/www.joypad.ch\/","name":"Joypad.ch","description":"Die Videospiel-, Technologie- und Filmseite f\u00fcr das Tessin und die italienischsprachige Schweiz","publisher":{"@id":"https:\/\/www.joypad.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joypad.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.joypad.ch\/#organization","name":"Joypad.ch","url":"https:\/\/www.joypad.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","contentUrl":"https:\/\/www.joypad.ch\/wp-content\/uploads\/2016\/01\/Logo_def_bn.jpg","width":6671,"height":902,"caption":"Joypad.ch"},"image":{"@id":"https:\/\/www.joypad.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.joypad.ch","https:\/\/x.com\/JoypadCH","https:\/\/www.instagram.com\/joypadch\/","https:\/\/www.youtube.com\/c\/JoypadCH","https:\/\/www.tiktok.com\/@mrpipistro"]},{"@type":"Person","@id":"https:\/\/www.joypad.ch\/#\/schema\/person\/d7375963dc860aac116f9733865d5b74","name":"Dave","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e539e646f8c7d727043eab27fcbf1a782aadf166386409aaa49da51e79e047?s=96&d=mm&r=g","caption":"Dave"},"description":"Chefredakteur von Joypad, Sie finden ihn auch in sozialen Netzwerken @MrPipistro","sameAs":["https:\/\/www.joypad.ch","www.instagram.com\/joypadch","www.youtube.com\/@JoypadCH"],"url":"https:\/\/www.joypad.ch\/de\/author\/dave\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/15961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/comments?post=15961"}],"version-history":[{"count":0,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/posts\/15961\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/media?parent=15961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/categories?post=15961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joypad.ch\/de\/wp-json\/wp\/v2\/tags?post=15961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}